{"id":66802,"date":"2026-09-02T06:57:46","date_gmt":"2026-09-02T06:57:46","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/09\/02\/mp-solicita-rechazar-apelacion-a-condenados-por-borrar-antecedentes-penales-a-cambio-de-sobornos\/"},"modified":"2026-09-02T06:57:46","modified_gmt":"2026-09-02T06:57:46","slug":"mp-solicita-rechazar-apelacion-a-condenados-por-borrar-antecedentes-penales-a-cambio-de-sobornos","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/09\/02\/mp-solicita-rechazar-apelacion-a-condenados-por-borrar-antecedentes-penales-a-cambio-de-sobornos\/","title":{"rendered":"MP solicita rechazar apelaci\u00f3n a condenados por borrar antecedentes penales a cambio de sobornos"},"content":{"rendered":"<div>\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.-<\/strong> El Ministerio P\u00fablico solicit\u00f3 este martes a la Tercera Sala Penal de la Corte de Apelaci\u00f3n del Distrito Nacional que rechace los recursos de apelaci\u00f3n interpuestos por cuatro de los condenados a prisi\u00f3n por formar parte de la red que se dedicaba a borrar y alterar antecedentes penales a cambio de sobornos y que fue desmantelada con la Operaci\u00f3n Gavil\u00e1n.<\/p>\n<p class=\"wp-block-paragraph\">Eduardo Vel\u00e1zquez y Miguel Crucey, fiscales litigantes adscritos a la Direcci\u00f3n General de Persecuci\u00f3n del Ministerio P\u00fablico, presentaron ante el tribunal de alzada las pruebas por las que Luis Pe\u00f1a Cede\u00f1o, V\u00edctor Gilberto Mercedes, Jos\u00e9 Ram\u00f3n Quezada y Pilar Irene Trinidad fueron condenados a 10 a\u00f1os de prisi\u00f3n por el Cuarto Tribunal Colegiado en agosto del a\u00f1o 2025.<\/p>\n<p class=\"wp-block-paragraph\">El fiscal Vel\u00e1zquez dijo que el Ministerio P\u00fablico prob\u00f3 la acusaci\u00f3n en su momento, y m\u00e1s all\u00e1 de toda duda razonable, y con pruebas contundentes.<\/p>\n<p class=\"wp-block-paragraph\">\u00abLo que hemos conocido son cuatro recursos que, realmente, para los jueces, y para nosotros como Ministerio P\u00fablico, est\u00e1n ac\u00e9falos en el sentido de que no tienen sustento ni elementos de prueba que puedan aportarles a los jueces de esta alzada; que puedan, al momento de la deliberaci\u00f3n, poder revocar la decisi\u00f3n, m\u00e1xime con una acusaci\u00f3n y una sentencia que fue emitida en favor de la sociedad y el Ministerio P\u00fablico en base a hechos y derecho debidamente justificada y motivada\u00bb, subray\u00f3.<\/p>\n<p class=\"wp-block-paragraph\">El representante del Ministerio P\u00fablico se mostr\u00f3 confiado en que la sentencia ser\u00e1 ratificada. \u00abS\u00ed, entendemos que s\u00ed. Los cuatro recursos van a ser desestimados y confirmada la decisi\u00f3n del Cuarto Tribunal Colegiado, el cual conden\u00f3 a cada imputado a 10 a\u00f1os de prisi\u00f3n\u00bb, dijo en respuesta a preguntas de la prensa.<\/p>\n<p class=\"wp-block-paragraph\">Sobre los alegatos expuestos por los procesados al hacer uso de su defensa material, dijo que \u00abesa es su defensa material, que la ampara la Constituci\u00f3n y el C\u00f3digo Procesal Penal a cada imputado, de decir lo que entienda de lugar\u00bb.<\/p>\n<p class=\"wp-block-paragraph\">La corte, integrada por los jueces Pedro S\u00e1nchez Rivera (presidente), Nancy Joaqu\u00edn y Mariana Daneyda Garc\u00eda, se reserv\u00f3 el fallo para el 2 de octubre del a\u00f1o 2026.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Antecedentes del caso<\/strong><\/p>\n<p class=\"wp-block-paragraph\">En el mes de agosto del pasado a\u00f1o, a solicitud del Ministerio P\u00fablico, fueron impuestas 13 condenas contra miembros de la estructura criminal que fueron procesados por borrar y modificar, a cambio de coimas, los registros de antecedentes penales de cientos de personas de la base de datos del Ministerio P\u00fablico.<\/p>\n<p class=\"wp-block-paragraph\">Las pruebas presentadas durante el juicio por el Ministerio P\u00fablico fueron acogidas por el tribunal de primera instancia, que las declar\u00f3 suficientes y contundentes, quedando destruida la presunci\u00f3n de inocencia de todos los procesados.<\/p>\n<p class=\"wp-block-paragraph\">El \u00f3rgano acusador demostr\u00f3 de forma objetiva y coherente la existencia de una estructura de criminalidad organizada, en la modalidad de Cibercrimen, que ejecut\u00f3 de manera deliberada maniobras inform\u00e1ticas fraudulentas de acceso il\u00edcito para alterar, borrar, modificar, afectar, eliminar y da\u00f1ar los datos y registros delictivos (fichas) de los ciudadanos que violentaron las leyes penales en el sistema de justicia dominicano, y que se encontraban registrados y almacenados en la base de datos de la infraestructura tecnol\u00f3gica de la Procuradur\u00eda General de la Rep\u00fablica y el Ministerio P\u00fablico.<\/p>\n<p class=\"wp-block-paragraph\">Esta actividad delictiva ejecutada por los condenados fue realizada con el \u00fanico objetivo de obtener beneficios econ\u00f3micos il\u00edcitos mediante el pago, la recepci\u00f3n de sobornos y corrupci\u00f3n.<\/p>\n<p class=\"wp-block-paragraph\"><strong>Evasi\u00f3n de la justicia y controles migratorios<\/strong><\/p>\n<p class=\"wp-block-paragraph\">La estructura criminal sancionada no solo constituy\u00f3 una grave amenaza a la seguridad jur\u00eddica y al sistema de justicia penal de la Rep\u00fablica Dominicana, sino que permiti\u00f3 la evasi\u00f3n, ante las autoridades, de personas que se encontraban con procesos penales ante los tribunales o que hab\u00edan cometido un il\u00edcito de cualquier naturaleza.<\/p>\n<p class=\"wp-block-paragraph\">Los condenados facilitaron la obtenci\u00f3n de documentos o pasaportes como consecuencia del borrado de los antecedentes penales en las bases de datos oficiales, que permitieron burlar los controles migratorios y fronterizos del pa\u00eds.<\/p>\n<p class=\"wp-block-paragraph\">Los elementos probatorios colectados por el Ministerio P\u00fablico, incluyendo testimonios, pruebas materiales, peritajes inform\u00e1ticos y financieros, audiovisuales, documentaci\u00f3n oficial y pruebas digitales irrefutables, legalmente incorporados en juicio, fueron valorados por el juzgado de primera instancia de manera coherente y arm\u00f3nica, quedando configurado un cuadro probatorio s\u00f3lido que demostr\u00f3 la participaci\u00f3n activa y consciente de los acusados, quienes fueron condenados en proporci\u00f3n al grado de participaci\u00f3n y la gravedad de los hechos que se les imputaron.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"SANTO DOMINGO.- El Ministerio P\u00fablico solicit\u00f3 este martes a la Tercera Sala&hellip;\n","protected":false},"author":1,"featured_media":66803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-66802","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/66802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=66802"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/66802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/66803"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=66802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=66802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=66802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}