{"id":55382,"date":"2026-07-15T15:24:34","date_gmt":"2026-07-15T15:24:34","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/rosa-santos-exhorta-a-honrar-el-legado-de-duarte-durante-acto-por-el-150-aniversario-de-su-fallecimiento-el-nuevo-diario-republica-dominicana\/"},"modified":"2026-07-15T15:24:34","modified_gmt":"2026-07-15T15:24:34","slug":"rosa-santos-exhorta-a-honrar-el-legado-de-duarte-durante-acto-por-el-150-aniversario-de-su-fallecimiento-el-nuevo-diario-republica-dominicana","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/rosa-santos-exhorta-a-honrar-el-legado-de-duarte-durante-acto-por-el-150-aniversario-de-su-fallecimiento-el-nuevo-diario-republica-dominicana\/","title":{"rendered":"Rosa Santos exhorta a honrar el legado de Duarte durante acto por el 150 aniversario de su fallecimiento \u2013 El Nuevo Diario (Rep\u00fablica Dominicana)"},"content":{"rendered":"<div>\n<div id=\"gemini-summary-wrapper\" class=\"mb-3\">\n                <button id=\"btn-get-summary\" class=\"gemini-btn\" data-post-id=\"3199142\" data-post-title=\"Rosa Santos exhorta a honrar el legado de Duarte durante acto por el 150 aniversario de su fallecimiento\"><br \/>\n                    Leer resumen <b class=\"d-none d-md-inline\">de la noticia<\/b> (IA) <span>CLICK AQU\u00cd<\/span><br \/>\n                <\/button><\/p>\n<div id=\"gemini-loading\" class=\"mb-3\">\n<p>                    <span>Analizando noticia\u2026 por favor espera.<\/span>\n                <\/div>\n<\/p><\/div>\n<p><strong>EL NUEVO DIARIO, SANTIAGO. \u2013<\/strong> La gobernadora provincial de Santiago, Rosa Santos, llam\u00f3 a los dominicanos a convertir el reconocimiento a los h\u00e9roes de la patria en una pr\u00e1ctica permanente y a asumir un compromiso activo con el desarrollo del pa\u00eds, durante el acto conmemorativo del\u00a0 150 aniversario del fallecimiento de Juan Pablo Duarte y D\u00edez.<\/p>\n<p>La representante del Poder Ejecutivo afirm\u00f3 que el legado del Padre de la Patria debe trascender las fechas conmemorativas tradicionales y permanecer presente en la conciencia de cada ciudadano.<\/p>\n<p>\u00abAs\u00ed como celebramos el 27 de Febrero y el 30 de Marzo, tambi\u00e9n debemos recordar la fecha de la partida de Duarte, porque su legado contin\u00faa fortaleciendo nuestra identidad como naci\u00f3n\u00bb, expres\u00f3.<\/p>\n<p>Durante su discurso, Santos destac\u00f3 que Duarte renunci\u00f3 a una vida de privilegios para dedicar su existencia a la causa independentista, pese a contar con oportunidades de permanecer en pa\u00edses como Francia o Estados Unidos.<\/p>\n<p>\u00abDuarte ten\u00eda una vida c\u00f3moda, acceso a una educaci\u00f3n privilegiada y pudo quedarse en cualquier lugar del mundo disfrutando de esas oportunidades. Sin embargo, decidi\u00f3 sacrificarlo todo para regresar y luchar por la libertad de la Rep\u00fablica Dominicana\u00bb, se\u00f1al\u00f3.<\/p>\n<p><img loading=\"lazy\" data-recalc-dims=\"1\" data-dominant-color=\"8a786d\" data-has-transparency=\"false\" style=\"--dominant-color: #8a786d;\" decoding=\"async\" class=\"alignnone size-large wp-image-3199208 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM-800x450.jpeg?resize=640%2C360&quality=100&ssl=1\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 800w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 400w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 768w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 1536w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 355w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 1600w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-8.32.58-AM.jpeg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"\/><\/p>\n<p>Asimismo, resalt\u00f3 que trabajar por la patria significa trabajar por el bienestar de todos los dominicanos y por el futuro de las nuevas generaciones.<\/p>\n<p>Durante la ceremonia tambi\u00e9n fue recordada la fundaci\u00f3n de La Trinitaria, el 16 de julio de 1838, organizaci\u00f3n creada por Duarte junto a un grupo de j\u00f3venes comprometidos con la independencia nacional bajo el lema \u00abDios, Patria y Libertad\u00bb, movimiento que dio paso a la proclamaci\u00f3n de la independencia el 27 de febrero de 1844.<\/p>\n<p>En su intervenci\u00f3n, Rosa Santos subray\u00f3 adem\u00e1s que Duarte so\u00f1\u00f3 con una Rep\u00fablica sustentada en el respeto a la ley, la justicia, la educaci\u00f3n y la igualdad de todos los ciudadanos, principios que consider\u00f3 indispensables para continuar fortaleciendo la democracia dominicana.<\/p>\n<p>La gobernadora record\u00f3 que, pese al destierro y la persecuci\u00f3n pol\u00edtica que enfrent\u00f3, Duarte jam\u00e1s abandon\u00f3 sus ideales y muri\u00f3 en Caracas, Venezuela, el 15 de julio de 1876, dejando un legado que, 150 a\u00f1os despu\u00e9s, contin\u00faa inspirando a la naci\u00f3n.<\/p>\n<p>Finalmente, reafirm\u00f3 el compromiso del Gobierno dominicano y de las instituciones educativas de preservar la memoria de Juan Pablo Duarte, Francisco del Rosario S\u00e1nchez, Mat\u00edas Ram\u00f3n Mella y los dem\u00e1s h\u00e9roes nacionales, con el objetivo de fortalecer el civismo, la identidad nacional y el amor por la patria entre las presentes y futuras generaciones.<\/p>\n<p><iframe loading=\"lazy\" title=\"Reproductor de video VideoPress\" aria-label=\"Reproductor de video VideoPress\" width=\"640\" height=\"360\" src=\"https:\/\/videopress.com\/embed\/yFtJGPUf?hd=1&cover=1&loop=0&autoPlay=0&permalink=1&muted=0&controls=1&playsinline=0&useAverageColor=0&preloadContent=metadata\" frameborder=\"0\" allowfullscreen=\"\" data-resize-to-parent=\"true\" allow=\"clipboard-write; presentation\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Reproductor de video VideoPress\" aria-label=\"Reproductor de video VideoPress\" width=\"640\" height=\"360\" src=\"https:\/\/videopress.com\/embed\/ZSOiOe3q?hd=1&cover=1&loop=0&autoPlay=0&permalink=1&muted=0&controls=1&playsinline=0&useAverageColor=0&preloadContent=metadata\" frameborder=\"0\" allowfullscreen=\"\" data-resize-to-parent=\"true\" allow=\"clipboard-write; presentation\"><\/iframe><\/p>\n<p><h3 id=\"relacionado\" class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<p>\t\t\t\t\t\t<!-- .entry-footer --><br \/>\n\t\t\t\t\t\t<!-- \n\n<div data-type=\"_mgwidget\" data-widget-id=\"1743501\"><\/div>\n\n  -->\n\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"Leer resumen de la noticia (IA) CLICK AQU\u00cd Analizando noticia\u2026 por favor&hellip;\n","protected":false},"author":1,"featured_media":55383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55382","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55382"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55383"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}