{"id":55321,"date":"2026-07-15T08:57:36","date_gmt":"2026-07-15T08:57:36","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/camara-de-diputados-preve-aprobar-la-reforma-al-codigo-penal-esta-semana\/"},"modified":"2026-07-15T08:57:36","modified_gmt":"2026-07-15T08:57:36","slug":"camara-de-diputados-preve-aprobar-la-reforma-al-codigo-penal-esta-semana","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/camara-de-diputados-preve-aprobar-la-reforma-al-codigo-penal-esta-semana\/","title":{"rendered":"C\u00e1mara de Diputados prev\u00e9 aprobar la reforma al C\u00f3digo Penal esta semana"},"content":{"rendered":"<div>\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.<\/strong>\u2013 La C\u00e1mara de Diputados prev\u00e9 debatir y aprobar el proyecto de modificaci\u00f3n al C\u00f3digo Penal esta misma semana, seg\u00fan inform\u00f3 su presidente, Alfredo Pacheco. <\/p>\n<p class=\"wp-block-paragraph\">El \u00f3rgano legislativo sesionar\u00e1 este jueves a la 1:00 p. m. y dej\u00f3 abierta una convocatoria extraordinaria para el viernes en caso de ser necesario para sancionar las enmiendas antes de que venza la actual legislatura ordinaria.<\/p>\n<p class=\"wp-block-paragraph\">El apuro del Congreso responde a que el nuevo C\u00f3digo Penal est\u00e1 programado para entrar en vigencia formal a corto plazo. Los legisladores buscan introducir y ratificar las correcciones antes de esa fecha l\u00edmite. <\/p>\n<p class=\"wp-block-paragraph\">El plan estipula que la c\u00e1mara baja apruebe el pliego de modificaciones a m\u00e1s tardar el viernes, permitiendo que el Senado agote el mismo proceso de revisi\u00f3n y votaci\u00f3n durante la semana siguiente, la cual marca el cierre definitivo de los trabajos legislativos.<\/p>\n<p class=\"wp-block-paragraph\">Para cumplir con este exigente cronograma, la comisi\u00f3n bicameral encargada del estudio t\u00e9cnico sostendr\u00e1 jornadas de trabajo continuo las tardes de este martes y mi\u00e9rcoles, concluyendo el jueves por la ma\u00f1ana para estructurar el informe que se presentar\u00e1 en el pleno. Las prisas legislativas coinciden con el l\u00edmite del plazo de recepci\u00f3n de observaciones ciudadanas e institucionales. <\/p>\n<p class=\"wp-block-paragraph\">El presidente de los diputados, Alfredo Pacheco, inst\u00f3 formalmente a sus colegas a despejar sus agendas, suspender viajes y posponer compromisos personales a fin de asegurar de forma estricta el qu\u00f3rum legal requerido en las sesiones decisivas.<\/p>\n<p class=\"wp-block-paragraph\">Apenas una semana despu\u00e9s de abrirse las mesas de di\u00e1logo en el Congreso, el equipo de legisladores ya ha acumulado m\u00e1s de una veintena de propuestas t\u00e9cnicas de enmienda provenientes de diversos sectores de la sociedad civil. Los puntos neur\u00e1lgicos y m\u00e1s debatidos se concentran en reformas a los art\u00edculos relacionados con delitos de opini\u00f3n, tales como la difamaci\u00f3n, la injuria y el ultraje.<\/p>\n<p class=\"wp-block-paragraph\"> Sectores civiles y gremios period\u00edsticos exigen separar de forma tajante las imputaciones de la vida privada frente a los hechos de inter\u00e9s p\u00fablico para salvaguardar la libertad de prensa. <\/p>\n<p class=\"wp-block-paragraph\">Asimismo, la Alianza Dominicana Contra la Corrupci\u00f3n deposit\u00f3 un pliego de ajustes espec\u00edficos destinados a asegurar la plena compatibilidad del texto normativo penal con la Constituci\u00f3n y los tratados internacionales. Al mismo tiempo, las evaluaciones t\u00e9cnicas del Ministerio de Justicia buscan redefinir los alcances y multas en los delitos de cuello blanco y la responsabilidad jur\u00eddica empresarial.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"SANTO DOMINGO.\u2013 La C\u00e1mara de Diputados prev\u00e9 debatir y aprobar el proyecto&hellip;\n","protected":false},"author":1,"featured_media":55322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55321","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55321"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55322"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}