{"id":55305,"date":"2026-07-15T07:52:42","date_gmt":"2026-07-15T07:52:42","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/la-produccion-industrial-china-supera-expectativas-al-crecer-un-53-en-junio\/"},"modified":"2026-07-15T07:52:42","modified_gmt":"2026-07-15T07:52:42","slug":"la-produccion-industrial-china-supera-expectativas-al-crecer-un-53-en-junio","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/la-produccion-industrial-china-supera-expectativas-al-crecer-un-53-en-junio\/","title":{"rendered":"La producci\u00f3n industrial china supera expectativas al crecer un 5,3 % en junio"},"content":{"rendered":"<div id=\"nota-texto\">\n<p>La producci\u00f3n industrial en <strong>China<\/strong> creci\u00f3 un 5,3 % interanual en junio, lo que supone una lectura 0,8 puntos m\u00e1s positiva que la anterior, mientras las ventas minoristas rebotaron de su primer descenso desde 2022 y la inversi\u00f3n en activos fijos sigui\u00f3 desplom\u00e1ndose, lastrada por la crisis inmobiliaria.<\/p>\n<p>Seg\u00fan los datos oficiales divulgados hoy por la <strong><a href=\"https:\/\/noticiassin.com\/tag\/oficina-nacional-de-estadistica\/\" class=\"nsin-auto-tag-link\">Oficina Nacional de Estad\u00edstica<\/a><\/strong> (<strong>ONE<\/strong>) del pa\u00eds asi\u00e1tico, la producci\u00f3n industrial queda, asimismo, por encima de los pron\u00f3sticos m\u00e1s extendidos entre los analistas, que esperaban un repunte adicional, pero de car\u00e1cter leve, hasta en torno a un 4,6 %.<\/p>\n<p>De los tres grandes sectores en los que la <strong>ONE<\/strong> dividi\u00f3 este indicador, el que m\u00e1s aument\u00f3 su producci\u00f3n en junio fue el de producci\u00f3n y suministro de electricidad, calefacci\u00f3n, gas y agua (+7,4 %), seguido del manufacturero (+6 %), mientras que el minero marc\u00f3 la nota discordante al descender un 2,2 %.<\/p>\n<p>En el acumulado del primer semestre, la producci\u00f3n industrial china creci\u00f3 un<strong> 5,4 % frente al mismo per\u00edodo de 2025.<\/strong><\/p>\n<p>La instituci\u00f3n estad\u00edstica tambi\u00e9n hizo hoy p\u00fablicos otros datos de junio, como las ventas al por menor, indicador clave para medir el estado del consumo, las cuales rebotaron tras su ca\u00edda del 0,6 % en mayo \u2014la primera desde 2022, lo que levant\u00f3 todav\u00eda m\u00e1s la alarma sobre el estado de la demanda a nivel nacional\u2014 para crecer un 1 % en junio.<\/p>\n<div class=\"nbs-subscribe-box \">\n<p>Suscribete al newsletter de Noticias SIN<\/p>\n<\/div>\n<p>Esta cifra supone, asimismo, superar ampliamente las expectativas de los expertos, que anticipaban que las ventas volver\u00edan a terreno positivo, pero por poco, <strong>situando su pron\u00f3stico en un 0,1 % interanual.<\/strong><\/p>\n<p>Tambi\u00e9n fue una sorpresa positiva la evoluci\u00f3n de la tasa oficial de desempleo en zonas urbanas, ya que baj\u00f3 <strong>del 5,1 % al 5 % cuando los analistas no esperaban movimiento alguno.<\/strong><\/p>\n<p>Por su parte, la inversi\u00f3n en activos fijos, la cual pas\u00f3 de crecer un 3,2 % en 2024 a caer un 3,8 % en 2025, lastrada por la crisis del sector inmobiliario, ampli\u00f3 su bajada a un 5,7 % en el acumulado del primer semestre, frente al 4,1 % que hab\u00eda registrado hasta mayo.<\/p>\n<p>Si bien el inmobiliario, como viene siendo habitual, ampli\u00f3 su desplome hasta el 18 % entre enero y junio, los otros dos grandes sectores en los que la <strong>ONE<\/strong> mide la inversi\u00f3n tambi\u00e9n marcaron cifras negativas: la destinada a manufactura cay\u00f3 un 1,2 % y la de infraestructura, que hab\u00eda sido la \u00fanica en resistir en la anterior actualizaci\u00f3n de este indicador, baj\u00f3 un 2,4 % en el semestre.<\/p>\n<p>La <strong>ONE<\/strong> indic\u00f3 tambi\u00e9n que las ventas comerciales de inmuebles nuevos, medidas sobre \u00e1rea de suelo, cayeron un 11,6 % interanual en la primera mitad de 2026, ampliando su descenso en 0,8 puntos frente al acumulado hasta mayo.\u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"La producci\u00f3n industrial en China creci\u00f3 un 5,3 % interanual en junio,&hellip;\n","protected":false},"author":1,"featured_media":55306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-55305","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55305"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55306"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}