{"id":55282,"date":"2026-07-15T05:46:40","date_gmt":"2026-07-15T05:46:40","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/leidsa-entrega-cheque-de-30-millones-a-artesano-ganador-del-loto\/"},"modified":"2026-07-15T05:46:40","modified_gmt":"2026-07-15T05:46:40","slug":"leidsa-entrega-cheque-de-30-millones-a-artesano-ganador-del-loto","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/leidsa-entrega-cheque-de-30-millones-a-artesano-ganador-del-loto\/","title":{"rendered":"LEIDSA entrega cheque de 30 millones a artesano ganador del Loto"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong><strong>SANTO DOMINGO<\/strong>.-<\/strong> La <strong>Loter\u00eda Electr\u00f3nica Internacional Dominicana, S. A.<\/strong> (<strong>LEIDSA<\/strong>) inform\u00f3 que el Sr. <strong><a href=\"https:\/\/noticiassin.com\/tag\/blas-paulino-lopez\/\" class=\"nsin-auto-tag-link\">Blas Paulino L\u00f3pez<\/a><\/strong> recibi\u00f3 el premio de 30 millones de pesos, monto que ten\u00eda acumulado el sorteo <strong>Loto<\/strong> correspondiente al pasado s\u00e1bado 20 de junio.<\/p>\n<p>\u00a0<strong>Blas Paulino<\/strong>, un hombre que ha realizado todo tipo de labores agr\u00edcolas durante su vida y que, en los \u00faltimos a\u00f1os, se ha dedicado a artesano, trabajando el guano, fabricando sillas, mecedoras y todo tipo de art\u00edculos donde se utiliza como materia prima este material.<\/p>\n<p>Realiz\u00f3 una jugada seleccionada con los n\u00fameros: 1-7-17-20-23-34, en el punto de venta \u00abFarmacia Extra\u00bb, ubicado en la ave. <strong>Antonio Guzm\u00e1n Fern\u00e1ndez<\/strong>, <strong>La Joya<\/strong>, <strong>Santiago<\/strong>.<\/p>\n<h2 id=\"santiago-suma-otro-ganador-del-loto\" class=\"wp-block-heading\">Santiago suma otro ganador del Loto<\/h2>\n<p><strong>Blas Paulino<\/strong> se convierte en el millonario 504 que realiza <strong>LEIDSA<\/strong>, tu \u00fanica Loto, la f\u00e1brica de millonarios, y n\u00famero 99 de la provincia de <strong>Santiago de los Caballeros<\/strong>.<\/p>\n<p>Al recibir su cheque de 30 millones de pesos de mano del Lic. <strong>Manuel Abreu<\/strong>, director de sorteos de la empresa, el feliz millonario expres\u00f3: Me servir\u00e1n para, finalmente, a mis 80 a\u00f1os, poder retirarme a descansar\u201d.<\/p>\n<div class=\"nbs-subscribe-box \">\n<p>Suscribete al newsletter de Noticias SIN<\/p>\n<\/div>\n<h2 id=\"incentivos-para-el-punto-de-venta\" class=\"wp-block-heading\">Incentivos para el punto de venta<\/h2>\n<p><strong>LEIDSA<\/strong>, adem\u00e1s, entreg\u00f3 incentivos por 100 mil y 65 mil pesos al propietario y operador del punto de venta por haber vendido el ticket ganador.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"SANTO DOMINGO.- La Loter\u00eda Electr\u00f3nica Internacional Dominicana, S. A. (LEIDSA) inform\u00f3 que&hellip;\n","protected":false},"author":1,"featured_media":55283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55282","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55282"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55283"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}