{"id":55257,"date":"2026-07-15T03:22:43","date_gmt":"2026-07-15T03:22:43","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/accidente-entre-motocicleta-y-patana-deja-un-muerto-y-una-mujer-herida-en-la-john-f-kennedy-el-nuevo-diario-republica-dominicana\/"},"modified":"2026-07-15T03:22:43","modified_gmt":"2026-07-15T03:22:43","slug":"accidente-entre-motocicleta-y-patana-deja-un-muerto-y-una-mujer-herida-en-la-john-f-kennedy-el-nuevo-diario-republica-dominicana","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/15\/accidente-entre-motocicleta-y-patana-deja-un-muerto-y-una-mujer-herida-en-la-john-f-kennedy-el-nuevo-diario-republica-dominicana\/","title":{"rendered":"Accidente entre motocicleta y patana deja un muerto y una mujer herida en la John F. Kennedy \u2013 El Nuevo Diario (Rep\u00fablica Dominicana)"},"content":{"rendered":"<div>\n<div id=\"gemini-summary-wrapper\" class=\"mb-3\">\n                <button id=\"btn-get-summary\" class=\"gemini-btn\" data-post-id=\"3198814\" data-post-title=\"Accidente entre motocicleta y patana deja un muerto y una mujer herida en la John F. Kennedy\"><br \/>\n                    Leer resumen <b class=\"d-none d-md-inline\">de la noticia<\/b> (IA) <span>CLICK AQU\u00cd<\/span><br \/>\n                <\/button><\/p>\n<div id=\"gemini-loading\" class=\"mb-3\">\n<p>                    <span>Analizando noticia\u2026 por favor espera.<\/span>\n                <\/div>\n<\/p><\/div>\n<p class=\"isSelectedEnd\">EL NUEVO DIARIO, SANTO DOMINGO.-\u00a0 Un accidente de tr\u00e1nsito registrado este martes en la avenida John F. Kennedy dej\u00f3 como saldo un hombre fallecido y una mujer gravemente herida, mientras las autoridades trabajan para establecer las circunstancias de la colisi\u00f3n e identificar al conductor de una patana que, seg\u00fan los reportes preliminares, abandon\u00f3 la escena.<\/p>\n<p class=\"isSelectedEnd\">El hecho ocurri\u00f3 cerca de las 6:00 de la tarde, en las inmediaciones de la calle Paseo de los Ferreteros. La v\u00edctima mortal viajaba en una motocicleta junto a una mujer cuando ambos se vieron involucrados en el choque con el veh\u00edculo pesado.<\/p>\n<p class=\"isSelectedEnd\">Tras recibir la alerta, unidades del Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9-1-1, agentes de la Polic\u00eda Nacional y personal del Instituto Nacional de Ciencias Forenses (Inacif) se trasladaron al lugar para asistir a los afectados y realizar las diligencias correspondientes.<\/p>\n<p class=\"isSelectedEnd\">Mientras el cuerpo del motociclista era levantado por el Inacif, la mujer fue estabilizada por los param\u00e9dicos y trasladada de urgencia a un centro de salud, donde recibe atenci\u00f3n m\u00e9dica.<\/p>\n<p class=\"isSelectedEnd\">Un oficial de la Polic\u00eda, identificado \u00fanicamente como Reyes, inform\u00f3 que el fallecido no hab\u00eda sido identificado al cierre de las labores realizadas en la escena.<\/p>\n<p class=\"isSelectedEnd\">Personas que se encontraban en el lugar indicaron que el hombre laboraba ofreciendo servicios de transporte mediante la plataforma Uber y que, al momento del accidente, trasladaba a la pasajera que result\u00f3 lesionada.<\/p>\n<p>El suceso provoc\u00f3 una importante ralentizaci\u00f3n del tr\u00e1nsito en la avenida John F. Kennedy durante varias horas, mientras las autoridades retiraban los veh\u00edculos involucrados y recopilaban evidencias para determinar c\u00f3mo ocurri\u00f3 el accidente.<\/p>\n<p><h3 id=\"relacionado\" class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<p>\t\t\t\t\t\t<!-- .entry-footer --><br \/>\n\t\t\t\t\t\t<!-- \n\n<div data-type=\"_mgwidget\" data-widget-id=\"1743501\"><\/div>\n\n  -->\n\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"Leer resumen de la noticia (IA) CLICK AQU\u00cd Analizando noticia\u2026 por favor&hellip;\n","protected":false},"author":1,"featured_media":55258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55257","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55257"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55258"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}