{"id":55202,"date":"2026-07-14T22:11:09","date_gmt":"2026-07-14T22:11:09","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/14\/omar-fernandez-hubiese-querido-cadena-perpetua-para-violadores-afirma-se-modificara-cp-para-garantizar-libre-expresion\/"},"modified":"2026-07-14T22:11:09","modified_gmt":"2026-07-14T22:11:09","slug":"omar-fernandez-hubiese-querido-cadena-perpetua-para-violadores-afirma-se-modificara-cp-para-garantizar-libre-expresion","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/14\/omar-fernandez-hubiese-querido-cadena-perpetua-para-violadores-afirma-se-modificara-cp-para-garantizar-libre-expresion\/","title":{"rendered":"Omar Fern\u00e1ndez: \u201cHubiese querido cadena perpetua para violadores\u201d; afirma se modificar\u00e1 CP para garantizar libre expresi\u00f3n"},"content":{"rendered":"<p><i class=\"bi bi-camera-fill\" style=\"font-size:18px; color:var(--rojo)\"\/> Omar Fern\u00e1ndez: \u201cHubiese querido cadena perpetua para violadores\u201d; afirma se modificar\u00e1 CP para garantizar libre expresi\u00f3n \u2013 (Ilustraci\u00f3n: El Nuevo Diario)<\/p>\n<div>\n<div id=\"gemini-summary-wrapper\" class=\"mb-3\">\n                <button id=\"btn-get-summary\" class=\"gemini-btn\" data-post-id=\"3198442\" data-post-title=\"Omar Fern\u00e1ndez: \u201cHubiese querido cadena perpetua para violadores\u201d; afirma se modificar\u00e1 CP para garantizar libre expresi\u00f3n\"><br \/>\n                    Leer resumen <b class=\"d-none d-md-inline\">de la noticia<\/b> (IA) <span>CLICK AQU\u00cd<\/span><br \/>\n                <\/button><\/p>\n<div id=\"gemini-loading\" class=\"mb-3\">\n<p>                    <span>Analizando noticia\u2026 por favor espera.<\/span>\n                <\/div>\n<\/p><\/div>\n<p>EL NUEVO DIARIO, SANTO DOMINGO. -El senador por el Distrito Nacional, Omar Fern\u00e1ndez, se\u00f1al\u00f3 que el cualquier aspecto que afecte el derecho a expresarse libremente debe ser modificado en favor de la ciudadan\u00eda.<\/p>\n<p>Manifest\u00f3 que cualquier error contemplado en el c\u00f3digo pen<\/p>\n<p><iframe loading=\"lazy\" title=\"Reproductor de video VideoPress\" aria-label=\"Reproductor de video VideoPress\" width=\"640\" height=\"360\" src=\"https:\/\/videopress.com\/embed\/tC9DNu13?hd=1&cover=1&loop=0&autoPlay=0&permalink=1&muted=0&controls=1&playsinline=0&useAverageColor=0&preloadContent=metadata\" frameborder=\"0\" allowfullscreen=\"\" data-resize-to-parent=\"true\" allow=\"clipboard-write; presentation\"><\/iframe><\/p>\n<p>al debe ser corregido en esta comisi\u00f3n, entendiendo que no siempre se logra lo que se desea.<\/p>\n<p>\u201cPor ejemplo yo hubiese querido cadena perpetua para violadores de menores, o sanciones m\u00e1s severas a los traficantes de haitianos, y aunque lo propuse no me lo aprobaron\u201d, se\u00f1al\u00f3 el senador al ser abordado por la prensa previo a la sesi\u00f3n de trabajo.<\/p>\n<p>Fern\u00e1ndez record\u00f3 que hace 11 meses durante los debates para la aprobaci\u00f3n del c\u00f3digo, enfatiz\u00f3 que el c\u00f3digo que se aprobaba era perfectible, y que necesitar\u00eda mejor en algunos puntos.<\/p>\n<p><h3 id=\"relacionado\" class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<p>\t\t\t\t\t\t<!-- .entry-footer --><br \/>\n\t\t\t\t\t\t<!-- \n\n<div data-type=\"_mgwidget\" data-widget-id=\"1743501\"><\/div>\n\n  -->\n\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"Omar Fern\u00e1ndez: \u201cHubiese querido cadena perpetua para violadores\u201d; afirma se modificar\u00e1 CP&hellip;\n","protected":false},"author":1,"featured_media":55203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55202","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55202"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55203"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}