{"id":55150,"date":"2026-07-14T17:37:24","date_gmt":"2026-07-14T17:37:24","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/14\/al-menos-cinco-muertos-tras-el-incendio-de-un-edificio-en-el-centro-de-bruselas\/"},"modified":"2026-07-14T17:37:24","modified_gmt":"2026-07-14T17:37:24","slug":"al-menos-cinco-muertos-tras-el-incendio-de-un-edificio-en-el-centro-de-bruselas","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/14\/al-menos-cinco-muertos-tras-el-incendio-de-un-edificio-en-el-centro-de-bruselas\/","title":{"rendered":"Al menos cinco muertos tras el incendio de un edificio en el centro de Bruselas"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong>Bruselas.<\/strong>\u2013 Al menos cinco personas que se encontraban en un ascensor han muerto en un incendio registrado a primera hora de este martes en un edificio en obras en el centro de <strong>Bruselas<\/strong>, seg\u00fan confirm\u00f3 la <strong>Fiscal\u00eda de Trabajo<\/strong> belga a la prensa local, que se\u00f1al\u00f3 que se busca a\u00fan a una persona, que posiblemente tambi\u00e9n ha fallecido.<\/p>\n<p>El rey <strong>Felipe<\/strong> de los belgas y el primer ministro del pa\u00eds, <strong>Baart de Wever<\/strong>, visitaron a primera hora de la tarde el lugar y conversaron con los servicios de emergencia que se encontraban all\u00ed.<\/p>\n<p>\u00abLos bomberos lograron encontrar una peque\u00f1a abertura en uno de estos ascensores y all\u00ed descubrimos a varias v\u00edctimas. A\u00fan no sabemos con exactitud cu\u00e1ntas personas hay. Podr\u00edan ser las seis personas desaparecidas, pero tambi\u00e9n podr\u00eda haber m\u00e1s en otro ascensor o en otro lugar\u00bb, dijo a los medios locales <strong>Brecht Speybrouck<\/strong>, portavoz de la <strong>Fiscal\u00eda<\/strong>, antes de que se iniciaran las labores de b\u00fasqueda.<\/p>\n<h2 id=\"investigacion-sobre-el-origen-del-fuego\" class=\"wp-block-heading\">Investigaci\u00f3n sobre el origen del fuego<\/h2>\n<p>El fuego, del que a\u00fan se desconocen las causas, comenz\u00f3 como un peque\u00f1o foco en la segunda planta del edificio y, a pesar de haber sido extinguido, las llamas lograron colarse por el hueco del ascensor, lo que afect\u00f3 a esta estructura.<\/p>\n<p>Los cad\u00e1veres fueron extra\u00eddos de uno de los ascensores del edificio, y los servicios de b\u00fasqueda sostuvieron que podr\u00eda haber uno m\u00e1s.<\/p>\n<div class=\"nbs-subscribe-box \">\n<p>Suscribete al newsletter de Noticias SIN<\/p>\n<\/div>\n<h2 id=\"victimas-y-heridos-del-incendio\" class=\"wp-block-heading\">V\u00edctimas y heridos del incendio<\/h2>\n<p>Dos personas con quemaduras han sido trasladadas al <strong>Hospital Militar de Neder-over-Heembeek<\/strong>, mientras que un bombero que sufri\u00f3 hipertermia fue atendido en el lugar.<\/p>\n<p>En el momento del incidente, m\u00e1s de 200 trabajadores se encontraban en el edificio, que se encuentra en obras para reconvertirlo en un complejo con restaurantes, oficinas, un hotel y apartamentos de lujo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Bruselas.\u2013 Al menos cinco personas que se encontraban en un ascensor han&hellip;\n","protected":false},"author":1,"featured_media":55151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-55150","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55150"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55151"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}