{"id":55121,"date":"2026-07-14T14:52:44","date_gmt":"2026-07-14T14:52:44","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/07\/14\/barrick-impulsa-programa-de-alfabetizacion-y-continuidad-educativa-en-beneficio-de-mas-de-200-jovenes-el-nuevo-diario-republica-dominicana\/"},"modified":"2026-07-14T14:52:44","modified_gmt":"2026-07-14T14:52:44","slug":"barrick-impulsa-programa-de-alfabetizacion-y-continuidad-educativa-en-beneficio-de-mas-de-200-jovenes-el-nuevo-diario-republica-dominicana","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/07\/14\/barrick-impulsa-programa-de-alfabetizacion-y-continuidad-educativa-en-beneficio-de-mas-de-200-jovenes-el-nuevo-diario-republica-dominicana\/","title":{"rendered":"Barrick impulsa programa de alfabetizaci\u00f3n y continuidad educativa en beneficio de m\u00e1s de 200 j\u00f3venes \u2013 El Nuevo Diario (Rep\u00fablica Dominicana)"},"content":{"rendered":"<p><i class=\"bi bi-camera-fill\" style=\"font-size:18px; color:var(--rojo)\"\/> Barrick impulsa programa de alfabetizaci\u00f3n y continuidad educativa en beneficio de m\u00e1s de 200 j\u00f3venes .-<\/p>\n<div>\n<div id=\"gemini-summary-wrapper\" class=\"mb-3\">\n                <button id=\"btn-get-summary\" class=\"gemini-btn\" data-post-id=\"3197707\" data-post-title=\"Barrick impulsa programa de alfabetizaci\u00f3n y continuidad educativa en beneficio de m\u00e1s de 200 j\u00f3venes\"><br \/>\n                    Leer resumen <b class=\"d-none d-md-inline\">de la noticia<\/b> (IA) <span>CLICK AQU\u00cd<\/span><br \/>\n                <\/button><\/p>\n<div id=\"gemini-loading\" class=\"mb-3\">\n<p>                    <span>Analizando noticia\u2026 por favor espera.<\/span>\n                <\/div>\n<\/p><\/div>\n<p>EL NUEVO DIARIO, COTU\u00cd.- Barrick Pueblo Viejo, en coordinaci\u00f3n con el Distrito Educativo 16-01 de Cotu\u00ed, realiz\u00f3 la jornada de preinscripci\u00f3n para el programa de alfabetizaci\u00f3n y continuidad educativa dirigido a j\u00f3venes y adultos. La iniciativa beneficiar\u00e1 a m\u00e1s de 200 personas y contribuir\u00e1 a fortalecer el acceso a la educaci\u00f3n en las comunidades de su \u00e1rea de influencia.<\/p>\n<p>El acto de lanzamiento se realiz\u00f3 en el sector Nuevos Horizontes, donde representantes de Barrick Pueblo Viejo, autoridades educativas y miembros de la comunidad compartieron los alcances de esta iniciativa y su impacto en el desarrollo de las personas. Con este programa, la empresa busca contribuir a la reducci\u00f3n del analfabetismo y ampliar las oportunidades educativas para j\u00f3venes y adultos que, por diferentes circunstancias, no pudieron concluir su formaci\u00f3n acad\u00e9mica.<\/p>\n<p><img loading=\"lazy\" data-recalc-dims=\"1\" data-dominant-color=\"b7adad\" data-has-transparency=\"false\" style=\"--dominant-color: #b7adad;\" decoding=\"async\" class=\"alignnone wp-image-3197730 size-full not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg?resize=640%2C426&quality=100&ssl=1\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg 1600w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg 400w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg 800w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg 768w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg 1536w, https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/07\/Barrick2.jpeg 1280w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\"\/><\/p>\n<p>El programa, desarrollado en coordinaci\u00f3n con el Ministerio de Educaci\u00f3n, brinda a personas de 15 a\u00f1os en adelante la oportunidad de aprender a leer y escribir, completar la educaci\u00f3n b\u00e1sica y culminar el bachillerato mediante un modelo educativo flexible y de calidad. Al finalizar cada nivel, los participantes recibir\u00e1n la certificaci\u00f3n oficial emitida por el Ministerio de Educaci\u00f3n.<\/p>\n<p>Adem\u00e1s de mejorar las competencias educativas de los participantes, la iniciativa promueve la inclusi\u00f3n social, fortalece el desarrollo familiar y ampl\u00eda las posibilidades de acceder a mejores oportunidades de empleo, generando un impacto positivo en la calidad de vida de las comunidades.<\/p>\n<p>Esta acci\u00f3n forma parte de la estrategia de inversi\u00f3n social de Barrick Pueblo Viejo, orientada a fortalecer las capacidades de las personas mediante programas que impulsan el desarrollo integral y a los compromisos asumidos en el plan de acci\u00f3n de reasentamiento con las comunidades<\/p>\n<p>A trav\u00e9s de iniciativas educativas como esta, Barrick Pueblo Viejo reafirma su compromiso con el desarrollo del capital humano, convencida de que la educaci\u00f3n es una de las herramientas m\u00e1s poderosas para transformar vidas y contribuir al progreso de las comunidades.<\/p>\n<p><h3 id=\"relacionado\" class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<p>\t\t\t\t\t\t<!-- .entry-footer --><br \/>\n\t\t\t\t\t\t<!-- \n\n<div data-type=\"_mgwidget\" data-widget-id=\"1743501\"><\/div>\n\n  -->\n\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"Barrick impulsa programa de alfabetizaci\u00f3n y continuidad educativa en beneficio de m\u00e1s&hellip;\n","protected":false},"author":1,"featured_media":55122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-55121","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=55121"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/55121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/55122"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=55121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=55121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=55121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}