{"id":43869,"date":"2026-05-26T18:21:58","date_gmt":"2026-05-26T18:21:58","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/26\/seguridad-crisis-de-salud-y-reformas-pendientes-para-el-proximo\/"},"modified":"2026-05-26T18:21:58","modified_gmt":"2026-05-26T18:21:58","slug":"seguridad-crisis-de-salud-y-reformas-pendientes-para-el-proximo","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/26\/seguridad-crisis-de-salud-y-reformas-pendientes-para-el-proximo\/","title":{"rendered":"seguridad, crisis de salud y reformas pendientes para el pr\u00f3ximo"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong>Bogot\u00e1<\/strong>. \u2013 El recrudecimiento del conflicto armado, la crisis del sistema de salud y las dificultades para avanzar en reformas sociales aparecen entre los principales desaf\u00edos que deber\u00e1 afrontar quien gane las elecciones presidenciales en <strong>Colombia<\/strong>, cuya primera vuelta ser\u00e1 este 31 de mayo, despu\u00e9s de cuatro a\u00f1os de Gobierno progresista.<\/p>\n<p>Las encuestas indican que la definici\u00f3n se dar\u00e1 en primera o segunda vuelta entre el izquierdista <strong>Iv\u00e1n Cepeda<\/strong>, considerado el sucesor del presidente <strong>Gustavo Petro<\/strong>; el ultraderechista <strong>Abelardo de la Espriella<\/strong> y la derechista <strong>Paloma Valencia<\/strong>.<\/p>\n<p>Para la analista pol\u00edtica <strong>Sandra Borda<\/strong>, el mayor reto ser\u00e1 la seguridad, en un contexto en el que grupos armados ilegales y organizaciones criminales han aumentado su presencia territorial en varias regiones del pa\u00eds.<\/p>\n<p>El efecto que tuvo el di\u00e1logo con grupos insurgentes y criminales fue que esos grupos han crecido en n\u00famero y en dominio territorial\u00bb, afirm\u00f3 <strong>Borda<\/strong> en una entrevista con <strong>EFE<\/strong> al referirse a la pol\u00edtica de \u2018paz total\u2019 del actual <strong>Gobierno<\/strong>.<\/p>\n<p><strong>Petro<\/strong> inici\u00f3 en 2022 di\u00e1logos con guerrillas, disidencias de las <strong>FARC<\/strong> y bandas criminales, pero estos grupos aprovecharon la situaci\u00f3n para aumentar su n\u00famero de integrantes, su control territorial y las disputas armadas en distintas regiones del pa\u00eds.<\/p>\n<p>El deterioro de la seguridad coincide, adem\u00e1s, con el d\u00e9cimo aniversario del acuerdo de paz firmado con la antigua guerrilla de las <strong>FARC<\/strong>, que redujo la intensidad del conflicto armado, pero no logr\u00f3 impedir el surgimiento y expansi\u00f3n de nuevas organizaciones criminales.<\/p>\n<h3 id=\"reformas-y-desigualdad\" class=\"wp-block-heading\">Reformas y desigualdad<\/h3>\n<p>En lo social, <strong>Borda<\/strong> considera que quien gane las elecciones heredar\u00e1 una agenda pendiente, despu\u00e9s de que el Ejecutivo de <strong>Petro<\/strong> no lograra sacar adelante la mayor\u00eda de las reformas prometidas para reducir la desigualdad.<\/p>\n<p>\u00abSomos el segundo pa\u00eds m\u00e1s desigual de <strong>Am\u00e9rica Latina<\/strong>, despu\u00e9s de <strong>Brasil<\/strong>\u00ab, record\u00f3.<\/p>\n<h3 id=\"narcotrafico-y-polarizacion\" class=\"wp-block-heading\">Narcotr\u00e1fico y polarizaci\u00f3n<\/h3>\n<p>La lucha contra el narcotr\u00e1fico aparece tambi\u00e9n entre los retos de quien gane las elecciones. Seg\u00fan <strong>Borda<\/strong>, el aumento de los cultivos il\u00edcitos y el fortalecimiento de grupos armados han complicado tanto la pol\u00edtica de seguridad como la relaci\u00f3n de <strong>Colombia<\/strong> con <strong>Estados Unidos<\/strong>.<\/p>\n<p><strong>Borda<\/strong> advirti\u00f3 igualmente sobre la creciente desconfianza hacia las instituciones p\u00fablicas y el auge de discursos antisistema, similares a los vistos en otros pa\u00edses de <strong>Am\u00e9rica Latina<\/strong>, como en <strong>Argentina<\/strong> con <strong>Javier Milei<\/strong>.<\/p>\n<p>Sin embargo, sostuvo que el<strong> pr\u00f3ximo Gobierno colombiano <\/strong>tendr\u00e1 m\u00e1s margen econ\u00f3mico que pol\u00edtico, ya que, pese al elevado d\u00e9ficit fiscal, buena parte de la poblaci\u00f3n no percibe una crisis econ\u00f3mica inmediata.<\/p>\n<p>El pa\u00eds no tiene la percepci\u00f3n de que estemos mal econ\u00f3micamente, y eso es lo que va a beneficiar al candidato del <strong>Gobierno<\/strong>\u00ab, afirm\u00f3 <strong>Borda<\/strong> sobre <strong>Cepeda<\/strong>.<\/p>\n<p>La experta alert\u00f3, no obstante, de que la polarizaci\u00f3n entre derecha e izquierda dificultar\u00e1 la posibilidad de alcanzar consensos en el <strong>Congreso<\/strong> para sacar adelante reformas estructurales.<\/p>\n<p>Advirti\u00f3 tambi\u00e9n que, independientemente del resultado electoral, el pr\u00f3ximo <strong>Gobierno<\/strong> afrontar\u00e1 un escenario de alta conflictividad pol\u00edtica porque una victoria de la derecha podr\u00eda provocar una avalancha de movilizaciones sociales, mientras que un triunfo de la izquierda mantendr\u00eda la din\u00e1mica de bloqueo legislativo entre sectores pol\u00edticos rivales.<\/p>\n<h3 id=\"crisis-del-sistema-de-salud\" class=\"wp-block-heading\">Crisis del sistema de salud<\/h3>\n<p>Entre los problemas m\u00e1s visibles aparece, adem\u00e1s, la crisis del sistema de salud, marcada por la escasez de medicamentos, las deudas de las Entidades Promotoras de Salud (<strong>EPS<\/strong>), el cierre de servicios y el aumento de quejas de pacientes por barreras de acceso a tratamientos.<\/p>\n<p>El sistema de salud colombiano est\u00e1 colapsado desde hace alg\u00fan tiempo\u00bb, asegur\u00f3 a <strong>EFE<\/strong> el director de la <strong>Federaci\u00f3n M\u00e9dica Colombiana<\/strong>, <strong>Diego Fernando Gonz\u00e1lez<\/strong>, quien atribuy\u00f3 parte de la crisis a la \u00abintermediaci\u00f3n financiera de los recursos p\u00fablicos en salud\u00bb.<\/p>\n<p>Seg\u00fan <strong>Gonz\u00e1lez<\/strong>, las <strong>EPS<\/strong> le deben millones de d\u00f3lares a hospitales, cl\u00ednicas y laboratorios, lo que ha generado un \u00abefecto domin\u00f3\u00bb sobre pacientes, y por eso lament\u00f3 que ning\u00fan candidato tenga una propuesta \u00abseria\u00bb para salir de esa crisis que pone en riesgo la vida de miles de personas que requieren atenci\u00f3n m\u00e9dica.<\/p>\n<p>No he le\u00eddo ni una propuesta seria de ning\u00fan candidato frente al tema de la salud\u00bb, afirm\u00f3 <strong>Gonz\u00e1lez<\/strong>.<\/p>\n<p>El dirigente gremial sostuvo, adem\u00e1s, que la crisis de la salud no es exclusiva del actual <strong>Gobierno<\/strong>, sino el resultado de problemas estructurales acumulados desde las administraciones de <strong>Juan Manuel Santos<\/strong> (2010-2018) e <strong>Iv\u00e1n Duque<\/strong> (2018-2022), periodos en los que tambi\u00e9n fueron cerradas <strong>EPS<\/strong> por problemas financieros.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Bogot\u00e1. \u2013 El recrudecimiento del conflicto armado, la crisis del sistema de&hellip;\n","protected":false},"author":1,"featured_media":43870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-43869","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/43869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=43869"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/43869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/43870"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=43869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=43869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=43869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}