{"id":40686,"date":"2026-05-13T20:51:46","date_gmt":"2026-05-13T20:51:46","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/henry-molina-designa-comision-para-evaluar-exigencias-de-jueces-que-convocan-a-paro-de-labores\/"},"modified":"2026-05-13T20:51:46","modified_gmt":"2026-05-13T20:51:46","slug":"henry-molina-designa-comision-para-evaluar-exigencias-de-jueces-que-convocan-a-paro-de-labores","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/henry-molina-designa-comision-para-evaluar-exigencias-de-jueces-que-convocan-a-paro-de-labores\/","title":{"rendered":"Henry Molina designa comisi\u00f3n para evaluar exigencias de jueces que convocan a paro de labores"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2025\/11\/Poder-Judicial-lanza-Plan-Justicia-del-Futuro-2034-a-nivel-nacional-3-355x200.jpg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #7a88b9;margin-bottom: 5px;clear:both;max-width: 100%\" data-has-transparency=\"false\" data-dominant-color=\"7a88b9\" \/><\/p>\n<p>EL NUEVO DIARIO, SANTO DOMINGO.- El presidente de la Suprema Corte de Justicia, Luis Henry Molina, design\u00f3 este mi\u00e9rcoles una comisi\u00f3n para evaluar las exigencias de m\u00e1s de 300 jueces que anunciaron paro de labores para el pr\u00f3ximo 21 de mayo, en el marco de un proceso de di\u00e1logo institucional orientado a atender las inquietudes del sector.<\/p>\n<p>La comisi\u00f3n est\u00e1 encabezada por el director de la Escuela Nacional de la Judicatura, \u00c1ngel Brito Pujols, y el titular de Comunicaciones del Poder Judicial, Javier Cabreja.<\/p>\n<p>Los jueces demandan aumento salarial y otras reivindicaciones orientadas a mejorar sus condiciones de vida y de trabajo, de manera que est\u00e9n acordes con la alta responsabilidad que implica el ejercicio de sus funciones dentro del sistema de justicia.<\/p>\n<p>Parte de los magistrados que respaldan el llamado a paro laborarles fueron recibido el d\u00eda de hoy por miembros del Poder Judicial en la Direcci\u00f3n General de la Carrera Judicial.<\/p>\n<p>La informaci\u00f3n fue ofrecida por Dante Daniel Ozuna, juez presidente de la Asociaci\u00f3n Dominicana de Jueces de Paz (Adojupa).<\/p>\n<p>Ozuna indic\u00f3 que la reuni\u00f3n tuvo como finalidad establecer un espacio de escucha activa entre las autoridades judiciales y los que apoyan la convocatoria a suspensi\u00f3n de trabajo, aclarando que los presentes no representan a la totalidad del sector, sino que fungieron como canal de comunicaci\u00f3n.<\/p>\n<p>\u201cEl objetivo fue realizar un di\u00e1logo con los jueces presentes. Cada uno de los participantes pudo intervenir y exponer sus planteamientos\u201d, expres\u00f3 el magistrado.<\/p>\n<p>Inform\u00f3 que la comisi\u00f3n designada levantar\u00e1 un informe con todas las intervenciones realizadas durante el encuentro, el cual ser\u00e1 presentado al Consejo del Poder Judicial para su evaluaci\u00f3n.<\/p>\n<p>En la reuni\u00f3n participaron, adem\u00e1s del magistrado Ozuna, los jueces Adriano Taveras y la magistrada Yokauris Morales, presidenta de la Federaci\u00f3n Nacional de Jueces, junto a otros representantes del sector.<\/p>\n<p>Pese al encuentro, a\u00fan se mantiene el llamado a paro de labores para el 21 de mayo, mientras se espera que surjan otros encuentros con el fin de buscar soluciones a las demandas de los jueces.<\/p>\n<p>NLP\/<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/henry-molina-designa-comision-para-evaluar-exigencias-de-jueces-que-convocan-a-paro-de-labores\/\">Henry Molina designa comisi\u00f3n para evaluar exigencias de jueces que convocan a paro de labores<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO, SANTO DOMINGO.- El presidente de la Suprema Corte de Justicia, Luis Henry Molina, design\u00f3 este mi\u00e9rcoles una comisi\u00f3n para evaluar las exigencias de m\u00e1s de 300 jueces que anunciaron paro de labores para el pr\u00f3ximo 21 de mayo, en el marco de un proceso de di\u00e1logo institucional orientado a atender las inquietudes<\/p>\n","protected":false},"author":1,"featured_media":40687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40686"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40687"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}