{"id":40680,"date":"2026-05-13T20:35:37","date_gmt":"2026-05-13T20:35:37","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/realizan-huelga-en-carretera-tenares-gaspar-hernandez-en-demanda-de-reconstruccion-de-la-via\/"},"modified":"2026-05-13T20:35:37","modified_gmt":"2026-05-13T20:35:37","slug":"realizan-huelga-en-carretera-tenares-gaspar-hernandez-en-demanda-de-reconstruccion-de-la-via","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/realizan-huelga-en-carretera-tenares-gaspar-hernandez-en-demanda-de-reconstruccion-de-la-via\/","title":{"rendered":"Realizan huelga en carretera Tenares-Gaspar Hern\u00e1ndez en demanda de reconstrucci\u00f3n de la v\u00eda"},"content":{"rendered":"<p><img decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/05\/Cierre-de-la-carretera-Tenares-Gaspar-Hernandez-355x200.png\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #727971;margin-bottom: 5px;clear:both;max-width: 100%\" loading=\"lazy\" data-has-transparency=\"false\" data-dominant-color=\"727971\" \/><\/p>\n<p>EL NUEVO DIARIO, TENARES.- La huelga convocada por 24 horas en demanda de la reconstrucci\u00f3n de la carretera Tenares-Gaspar Hern\u00e1ndez se desarrolla este mi\u00e9rcoles con amplio respaldo de organizaciones comunitarias, choferiles y comerciales de la zona monta\u00f1osa de este municipio, donde gran parte de las actividades permanecen paralizadas.<\/p>\n<p>Desde la noche del martes comenzaron las protestas con la quema de neum\u00e1ticos y la colocaci\u00f3n de obst\u00e1culos en distintos puntos de la v\u00eda, acciones realizadas por manifestantes que reclaman la intervenci\u00f3n urgente de la carretera, considerada una de las principales conexiones entre el Cibao Central y la costa atl\u00e1ntica.<\/p>\n<figure id=\"attachment_3117948\" aria-describedby=\"caption-attachment-3117948\" style=\"width: 1440px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"7b6455\" data-has-transparency=\"false\" style=\"--dominant-color: #7b6455\" class=\"size-full wp-image-3117948 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/05\/Huelga-en-Tenares.jpeg?resize=640%2C640&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" \/><figcaption id=\"caption-attachment-3117948\" class=\"wp-caption-text\">Cierre de la carretera Tenares-Gaspar Hern\u00e1ndez (Foto: Lincoln Minaya)<\/figcaption><\/figure>\n<p>Comunitarios denunciaron que el deterioro progresivo de la carretera ha alcanzado niveles cr\u00edticos, con frecuentes derrumbes, deslizamientos de tierra y fallas estructurales que dificultan el tr\u00e1nsito y representan un riesgo permanente para conductores y residentes.<\/p>\n<p>En el distrito municipal de Blanco Arriba, el comercio permanec\u00eda cerrado en m\u00e1s de un 90 %, mientras que el transporte p\u00fablico fue suspendido debido al respaldo ofrecido por los choferes al movimiento.<\/p>\n<p>El Sindicato de Transporte Tenares-Blanco Arriba inform\u00f3 que no exist\u00edan condiciones para operar sus unidades, debido a la magnitud de la protesta y al apoyo de los conductores a las demandas comunitarias.<\/p>\n<figure id=\"attachment_3117951\" aria-describedby=\"caption-attachment-3117951\" style=\"width: 1440px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"525d47\" data-has-transparency=\"false\" style=\"--dominant-color: #525d47\" class=\"size-full wp-image-3117951 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/05\/Carretera-Tenares-Gaspar-Hernandez.jpeg?resize=640%2C640&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"640\" \/><figcaption id=\"caption-attachment-3117951\" class=\"wp-caption-text\">Cierre de la carretera Tenares-Gaspar Hern\u00e1ndez (Foto: Lincoln Minaya)<\/figcaption><\/figure>\n<p>Durante el desarrollo de la huelga, varios ciudadanos fueron detenidos por agentes policiales, acusados de alterar el orden p\u00fablico mediante la quema de neum\u00e1ticos y el corte de \u00e1rboles que posteriormente fueron colocados en la carretera para obstaculizar el tr\u00e1nsito vehicular.<\/p>\n<p>Los organizadores del paro sostienen que la protesta busca llamar la atenci\u00f3n del Gobierno y del Ministerio de Obras P\u00fablicas y Comunicaciones (MOPC) sobre la necesidad urgente de rehabilitar esta importante v\u00eda, cuyo deterioro afecta directamente la producci\u00f3n agr\u00edcola, el comercio y la comunicaci\u00f3n entre provincias del nordeste y la costa norte.<\/p>\n<p>Ciudadanos consultados expresaron su esperanza de que la jornada sirva como un llamado de alerta para que las autoridades asuman la reconstrucci\u00f3n integral de la carretera Tenares-Gaspar Hern\u00e1ndez, una obra considerada vital para el desarrollo econ\u00f3mico y social de toda la regi\u00f3n.<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/realizan-huelga-en-carretera-tenares-gaspar-hernandez-en-demanda-de-reconstruccion-de-la-via\/\">Realizan huelga en carretera Tenares-Gaspar Hern\u00e1ndez en demanda de reconstrucci\u00f3n de la v\u00eda<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO, TENARES.- La huelga convocada por 24 horas en demanda de la reconstrucci\u00f3n de la carretera Tenares-Gaspar Hern\u00e1ndez se desarrolla este mi\u00e9rcoles con amplio respaldo de organizaciones comunitarias, choferiles y comerciales de la zona monta\u00f1osa de este municipio, donde gran parte de las actividades permanecen paralizadas. Desde la noche del martes comenzaron las<\/p>\n","protected":false},"author":1,"featured_media":40681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40680"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40681"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}