{"id":40666,"date":"2026-05-13T19:14:46","date_gmt":"2026-05-13T19:14:46","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/abinader-viajara-a-guyana-para-reunion-bilateral-con-presidente-mohamed-irfaan-ali\/"},"modified":"2026-05-13T19:14:46","modified_gmt":"2026-05-13T19:14:46","slug":"abinader-viajara-a-guyana-para-reunion-bilateral-con-presidente-mohamed-irfaan-ali","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/abinader-viajara-a-guyana-para-reunion-bilateral-con-presidente-mohamed-irfaan-ali\/","title":{"rendered":"Abinader viajar\u00e1 a Guyana para reuni\u00f3n bilateral con presidente Mohamed Irfaan Ali"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/05\/Abinader.jpg-355x200.jpeg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #827c77;margin-bottom: 5px;clear:both;max-width: 100%\" data-has-transparency=\"false\" data-dominant-color=\"827c77\" \/><\/p>\n<p data-start=\"0\" data-end=\"86\">EL NUEVO DIARIO, SANTO DOMINGO. \u2013 El presidente de la Rep\u00fablica, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Luis Abinader<\/span><\/span>, viajar\u00e1 la noche de este mi\u00e9rcoles a Guyana para sostener una reuni\u00f3n bilateral con el mandatario de esa naci\u00f3n sudamericana, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Mohamed Irfaan Ali<\/span><\/span>, y participar en la firma de acuerdos de cooperaci\u00f3n.<\/p>\n<p data-start=\"399\" data-end=\"566\">Seg\u00fan inform\u00f3 la Presidencia, ambos gobernantes dar\u00e1n seguimiento a acuerdos suscritos desde 2023 en \u00e1reas como energ\u00eda, seguridad alimentaria y cooperaci\u00f3n comercial.<\/p>\n<p data-start=\"568\" data-end=\"807\">A su llegada al aeropuerto de Georgetown, prevista para despu\u00e9s de las 7:00 de la noche, Abinader ser\u00e1 recibido con honores militares y posteriormente participar\u00e1 en una recepci\u00f3n oficial en la Casa de Gobierno junto al presidente guyan\u00e9s.<\/p>\n<p data-start=\"809\" data-end=\"1087\">El mandatario dominicano llegar\u00e1 a Guyana procedente de <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Panam\u00e1<\/span><\/span>, donde particip\u00f3 como orador principal en el Congreso Mundial de Zonas Francas y sostuvo encuentros con empresarios y con el presidente paname\u00f1o, <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Jos\u00e9 Ra\u00fal Mulino<\/span><\/span>.<\/p>\n<p data-start=\"1089\" data-end=\"1305\">Para el jueves est\u00e1 previsto un desayuno oficial ofrecido por Irfaan Ali en la Casa de Gobierno, seguido de una reuni\u00f3n bilateral entre las delegaciones de ambos pa\u00edses y la firma de un nuevo convenio de cooperaci\u00f3n.<\/p>\n<p data-start=\"1307\" data-end=\"1569\">Abinader estar\u00e1 acompa\u00f1ado por <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Eduardo Sanz Lovat\u00f3n<\/span><\/span>, ministro de Industria, Comercio y Mipymes; <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Biviana Riveiro<\/span><\/span>, directora ejecutiva de ProDominicana, y <span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">Ernesto Torres Pereyra<\/span><\/span>, embajador dominicano en Guyana.<\/p>\n<p data-start=\"1571\" data-end=\"1694\" data-is-last-node=\"\" data-is-only-node=\"\">El jefe de Estado prevee retornar al pa\u00eds el jueves 14 de mayo y el viernes continuar\u00e1 su agenda oficial en Rep\u00fablica Dominicana.<\/p>\n<p data-start=\"1571\" data-end=\"1694\" data-is-last-node=\"\" data-is-only-node=\"\">NLP\/<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/abinader-viajara-a-guyana-para-reunion-bilateral-con-presidente-mohamed-irfaan-ali\/\">Abinader viajar\u00e1 a Guyana para reuni\u00f3n bilateral con presidente Mohamed Irfaan Ali<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO, SANTO DOMINGO. \u2013 El presidente de la Rep\u00fablica, Luis Abinader, viajar\u00e1 la noche de este mi\u00e9rcoles a Guyana para sostener una reuni\u00f3n bilateral con el mandatario de esa naci\u00f3n sudamericana, Mohamed Irfaan Ali, y participar en la firma de acuerdos de cooperaci\u00f3n. Seg\u00fan inform\u00f3 la Presidencia, ambos gobernantes dar\u00e1n seguimiento a acuerdos<\/p>\n","protected":false},"author":1,"featured_media":40667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40666"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40667"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}