{"id":40662,"date":"2026-05-13T18:48:37","date_gmt":"2026-05-13T18:48:37","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/lionel-messi-sigue-siendo-el-jugador-mejor-pagado-de-la-mls-con-28m\/"},"modified":"2026-05-13T18:48:37","modified_gmt":"2026-05-13T18:48:37","slug":"lionel-messi-sigue-siendo-el-jugador-mejor-pagado-de-la-mls-con-28m","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/lionel-messi-sigue-siendo-el-jugador-mejor-pagado-de-la-mls-con-28m\/","title":{"rendered":"Lionel Messi sigue siendo el jugador mejor pagado de la MLS con $28M"},"content":{"rendered":"<div>\n<div class=\"c-detail__author full\">\n<div>\n<div class=\"c-detail__author__thumb\">\n<figure>\n                                <picture src=\"https:\/\/imagenes.hoy.com.do\/files\/image_square_xs\/uploads\/2025\/11\/18\/691c7d2b0f1b1.png\" data-size=\"w:40,h:40\">\n                                    <img decoding=\"async\" loading=\"lazy\" alt=\"Agencia AP\" width=\"40\" height=\"40\" src=\"https:\/\/imagenes.hoy.com.do\/files\/image_square_xs\/uploads\/2025\/11\/18\/691c7d2b0f1b1.png\"\/>\n                                <\/picture>\n                                <\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>                                                                                            <!-- --><\/p>\n<p class=\"paragraph\">El delantero del Inter Miami, <b>Lionel Messi<\/b>, sigue siendo el jugador mejor pagado de la <b>Major League Soccer<\/b> por tercer a\u00f1o consecutivo, aunque recibi\u00f3 un aumento significativo esta temporada.<\/p>\n<p class=\"paragraph\">Seg\u00fan datos publicados por la Asociaci\u00f3n de Jugadores de la MLS, la compensaci\u00f3n total garantizada de Messi esta temporada asciende a <b>28,33 millones de d\u00f3lares<\/b>, en comparaci\u00f3n con los 20,45 millones de d\u00f3lares de 2025.<\/p>\n<p class=\"paragraph\">Como en a\u00f1os anteriores, la cantidad refleja \u00fanicamente la parte correspondiente a los ingresos por juego de la remuneraci\u00f3n de Messi. En octubre pasado, Messi firm\u00f3 una extensi\u00f3n de contrato hasta la temporada 2028.<\/p>\n<p class=\"paragraph\">El propietario del Inter Miami, <b>Jorge Mas<\/b>, declar\u00f3 a Bloomberg en marzo que los ingresos totales de Messi oscilan entre <b>70 y 80 millones de d\u00f3lares anuales<\/b>. Se espera que Messi adquiera una participaci\u00f3n accionaria en el club una vez que se retire.<\/p>\n<p class=\"paragraph\">El delantero del LAFC, <b>Son Heung-min<\/b>, ocup\u00f3 el segundo lugar con una remuneraci\u00f3n garantizada de 11,15 millones de d\u00f3lares, seguido por su compa\u00f1ero del Inter Miami, Rodrigo De Paul, con 9,6 millones de d\u00f3lares. El delantero del San Diego, <b>Hirving &#8220;Chucky&#8221; Lozano<\/b>, se sit\u00faa en la cuarta posici\u00f3n con 9,33 millones de d\u00f3lares, a pesar de haber sido apartado del equipo y no haber jugado ni un solo minuto esta temporada. <b>Miguel Almir\u00f3n<\/b>, del Atlanta United, ocupa el quinto lugar con 7,87 millones de d\u00f3lares.<\/p>\n<p class=\"paragraph\">El sindicato suele realizar dos pagos de salarios al a\u00f1o.<\/p>\n<p class=\"paragraph\">Miami continu\u00f3 dominando la liga en cuanto a compensaci\u00f3n total garantizada por equipo. Los Herons alcanzaron los $54.57 millones, $7.7 millones m\u00e1s que el r\u00e9cord de la liga que establecieron en esta misma \u00e9poca hace un a\u00f1o.<\/p>\n<p class=\"paragraph\">Esta cantidad tambi\u00e9n duplica con creces la de todos los dem\u00e1s equipos, excepto dos. El desembolso total del LAFC asciende a $32.65 millones, seguido por el Atlanta United con $27.88 millones, el LA Galaxy con $26.43 millones y los Vancouver Whitecaps \u2014que est\u00e1n en venta y corren el riesgo de ser reubicados\u2014 con $24.56 millones.<\/p>\n<div class=\"c-detail__box \">\n<article class=\"c-detail__sumario \">\n<figure class=\"c-detail__sumario__thumb\" style=\"display: block;\">\n            <a href=\"#\" title=\"\">\n                <picture data-size=\"w:140,h:140\" loading=\"lazy\" src=\"https:\/\/imagenes.hoy.com.do\/files\/related_image\/files\/fp\/uploads\/2026\/05\/11\/6a023f4f10752.r_d.1312-559.jpeg\" data-full-src=\"https:\/\/imagenes.hoy.com.do\/uploads\/2026\/05\/11\/6a023f4f10752.jpeg\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"140\" alt=\"Lamine Yamal\" src=\"https:\/\/imagenes.hoy.com.do\/uploads\/2026\/05\/11\/6a023f4f10752.jpeg\"\/>\n                <\/picture>\n            <\/a><br \/>\n        <\/figure>\n<div class=\"c-detail__sumario__txt\">\n<p class=\"c-detail__sumario__signature\">\n                <strong><\/p>\n<p>                <strong class=\"c-detail__sumario__author \">Gabriel Alberto Hern\u00e1ndez Tiburcio<\/strong><\/strong>\n            <\/p>\n<\/p><\/div>\n<\/article>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El delantero del Inter Miami, Lionel Messi, sigue siendo el jugador mejor pagado de la Major League Soccer por tercer a\u00f1o consecutivo, aunque recibi\u00f3 un aumento significativo esta temporada. Seg\u00fan datos publicados por la Asociaci\u00f3n de Jugadores de la MLS, la compensaci\u00f3n total garantizada de Messi esta temporada asciende a 28,33 millones de d\u00f3lares, en<\/p>\n","protected":false},"author":1,"featured_media":40663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-40662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40662"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40663"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}