{"id":40639,"date":"2026-05-13T16:46:43","date_gmt":"2026-05-13T16:46:43","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/od-gymnastics-academy-se-consagra-doble-campeon-nacional\/"},"modified":"2026-05-13T16:46:43","modified_gmt":"2026-05-13T16:46:43","slug":"od-gymnastics-academy-se-consagra-doble-campeon-nacional","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/od-gymnastics-academy-se-consagra-doble-campeon-nacional\/","title":{"rendered":"OD Gymnastics Academy se consagra doble campe\u00f3n nacional&#8221;"},"content":{"rendered":"<div>\n<div class=\"c-detail__author full\">\n<div>\n<div class=\"c-detail__author__thumb\">\n<figure>\n                                <picture src=\"https:\/\/imagenes.hoy.com.do\/files\/image_square_xs\/uploads\/2025\/11\/10\/6911b3b5d935b.png\" data-size=\"w:40,h:40\">\n                                    <img decoding=\"async\" loading=\"lazy\" alt=\"Hoy .\" width=\"40\" height=\"40\" src=\"https:\/\/imagenes.hoy.com.do\/files\/image_square_xs\/uploads\/2025\/11\/10\/6911b3b5d935b.png\"\/>\n                                <\/picture>\n                                <\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>                                                                                            <!-- --><\/p>\n<p class=\"paragraph\">OD Gymnastics Academy volvi\u00f3 a hacer historia en la gimnasia art\u00edstica nacional al consagrarse como doble campe\u00f3n nacional, reafirmando su liderazgo y excelencia deportiva en la Rep\u00fablica Dominicana.<\/p>\n<p class=\"paragraph\">La academia logr\u00f3 un resultado extraordinario al conquistar 9 niveles campeones y 2 niveles sub campeones de un total de 11 niveles competitivos, consolid\u00e1ndose como el club m\u00e1s destacado del pa\u00eds y demostrando, una vez m\u00e1s, la calidad de su formaci\u00f3n t\u00e9cnica, disciplina y trabajo en equipo.<\/p>\n<p class=\"paragraph\">Con m\u00e1s de 16 a\u00f1os de trayectoria, OD Gymnastics Academy contin\u00faa siendo referencia en el desarrollo de atletas de alto rendimiento, formando campeonas dentro y fuera del escenario competitivo.<\/p>\n<div class=\"c-detail__box \">\n<article class=\"c-detail__sumario \">\n<figure class=\"c-detail__sumario__thumb\" style=\"display: block;\">\n            <a href=\"#\" title=\"\">\n                <picture data-size=\"w:140,h:140\" loading=\"lazy\" src=\"https:\/\/imagenes.hoy.com.do\/files\/related_image\/files\/fp\/uploads\/2026\/04\/23\/69ea516c794a6.r_d.611-494.jpeg\" data-full-src=\"https:\/\/imagenes.hoy.com.do\/uploads\/2026\/04\/23\/69ea516c794a6.jpeg\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"140\" height=\"140\" alt=\"Luis Abinader y Carolina Mej\u00eda\" src=\"https:\/\/imagenes.hoy.com.do\/uploads\/2026\/04\/23\/69ea516c794a6.jpeg\"\/>\n                <\/picture>\n            <\/a><br \/>\n        <\/figure>\n<\/article>\n<\/div>\n<p class=\"paragraph\">Este importante logro es el resultado del esfuerzo conjunto de atletas, entrenadores, padres y todo el staff t\u00e9cnico y administrativo que d\u00eda a d\u00eda trabaja con pasi\u00f3n y compromiso para seguir elevando la gimnasia dominicana.<\/p>\n<p class=\"paragraph\">La academia agradeci\u00f3 especialmente el respaldo constante de su CEO, la se\u00f1ora Massiel Javier, y la entrega incansable de su directora, Mery Luz Infante, quienes han sido pilares fundamentales en el crecimiento y \u00e9xito de la instituci\u00f3n.<\/p>\n<p class=\"paragraph\">\u201cEste triunfo pertenece a toda la familia OD Gymnastics y seguiremos trabajando para mantenernos en la cima de la gimnasia nacional\u201d, expresaron representantes de la academia.<\/p>\n<p class=\"paragraph\">OD Gymnastics Academy contin\u00faa demostrando que el trabajo, la disciplina y la pasi\u00f3n son la f\u00f3rmula del \u00e9xito, manteni\u00e9ndose como la academia n\u00famero uno de la Rep\u00fablica Dominicana<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>OD Gymnastics Academy volvi\u00f3 a hacer historia en la gimnasia art\u00edstica nacional al consagrarse como doble campe\u00f3n nacional, reafirmando su liderazgo y excelencia deportiva en la Rep\u00fablica Dominicana. La academia logr\u00f3 un resultado extraordinario al conquistar 9 niveles campeones y 2 niveles sub campeones de un total de 11 niveles competitivos, consolid\u00e1ndose como el club<\/p>\n","protected":false},"author":1,"featured_media":40640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-40639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40639"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40640"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}