{"id":40547,"date":"2026-05-13T08:32:40","date_gmt":"2026-05-13T08:32:40","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/asamblea-nacional-de-venezuela-respalda-acciones-legales-ante-la-cij-por-el-esequibo-con\/"},"modified":"2026-05-13T08:32:40","modified_gmt":"2026-05-13T08:32:40","slug":"asamblea-nacional-de-venezuela-respalda-acciones-legales-ante-la-cij-por-el-esequibo-con","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/asamblea-nacional-de-venezuela-respalda-acciones-legales-ante-la-cij-por-el-esequibo-con\/","title":{"rendered":"Asamblea Nacional de Venezuela respalda acciones legales ante la CIJ por el Esequibo con"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong>Caracas<\/strong>.- La <strong>Asamblea Nacional<\/strong> (<strong>AN<\/strong>, Parlamento) de <strong>Venezuela<\/strong> aprob\u00f3 este martes, por unanimidad, un acuerdo que respalda las acciones legales emprendidas por el Ejecutivo de <strong>Delcy Rodr\u00edguez<\/strong> en la disputa territorial que mantiene la naci\u00f3n caribe\u00f1a con <strong>Guyana<\/strong> sobre el <strong>Esequibo<\/strong>.<\/p>\n<p>El acuerdo, presentado por el diputado chavista <strong>Jos\u00e9 Vielma Mora<\/strong> en una sesi\u00f3n ordinaria transmitida por el canal estatal <strong>ANTV<\/strong>, ratifica el \u00abrespaldo absoluto\u00bb del Parlamento a \u00abtodas\u00bb las acciones emprendidas por el <strong>Gobierno<\/strong> en el \u00abmarco de la defensa integral\u00bb de su soberan\u00eda.<\/p>\n<p>Asimismo, acuerda que la <strong>AN<\/strong> coadyuve en la estrategia jur\u00eddica y diplom\u00e1tica que el Estado venezolano despliega ante la <strong>Corte Internacional de Justicia<\/strong> (<strong>CIJ<\/strong>), al tiempo que exhorta a los venezolanos a mantener la unidad nacional en torno a esta \u00abcausa justa\u00bb, que trasciende cualquier diferencia pol\u00edtica.<\/p>\n<h2 class=\"wp-block-heading\">Respaldo de la AN<\/h2>\n<p>Durante el debate, el diputado opositor <strong>Luis Emilio Rond\u00f3n<\/strong> dijo que esta disputa territorial ha unido a todo el pa\u00eds, lo que consider\u00f3 una \u00abbuena se\u00f1al\u00bb para <strong>Venezuela<\/strong>.<\/p>\n<p>El legislador reconoci\u00f3 que <strong>Venezuela<\/strong> no rescatar\u00e1 los 169.000 kil\u00f3metros que conforman el <strong>Esequibo<\/strong>, rico en recursos naturales, porque el <strong>Acuerdo de Ginebra<\/strong> de 1966 establece que se llegue a un acuerdo satisfactorio para ambas partes, por lo que, sostuvo, \u00abhay que hacer concesiones\u00bb.<\/p>\n<p>Por su parte, el presidente de la <strong>AN<\/strong>, <strong>Jorge Rodr\u00edguez<\/strong>, indic\u00f3 que, si <strong>Guyana<\/strong> ve que los venezolanos est\u00e1n unidos, \u00abno van a tener m\u00e1s remedio que cumplir con la ley\u00bb.<\/p>\n<p><strong>Rodr\u00edguez<\/strong> se\u00f1al\u00f3 que el <strong>Acuerdo de Ginebra<\/strong> busca llegar a un arreglo satisfactorio para ambas partes e indic\u00f3 que un tribunal no lograr\u00e1 esto, al asegurar que en esa instancia \u00absiempre se decide a favor o en contra de una de las partes\u00bb.<\/p>\n<h2 class=\"wp-block-heading\">Postura ante la CIJ<\/h2>\n<p>El lunes, la presidenta encargada de <strong>Venezuela<\/strong> calific\u00f3 de \u00ababsurdo antijur\u00eddico\u00bb el caso territorial que enfrenta a <strong>Guyana<\/strong> y <strong>Caracas<\/strong> ante la <strong>CIJ<\/strong> por la regi\u00f3n del <strong>Esequibo<\/strong> y la validez del <strong>Laudo Arbitral de 1899<\/strong>, que fij\u00f3 la frontera de <strong>Venezuela<\/strong> con la entonces <strong>Guayana Brit\u00e1nica<\/strong>.<\/p>\n<p>En una intervenci\u00f3n ante el m\u00e1ximo tribunal de las <strong>Naciones Unidas<\/strong>, <strong>Rodr\u00edguez<\/strong> se\u00f1al\u00f3 que \u00abninguna sentencia de esta Corte sobre la controversia territorial brindar\u00e1 una soluci\u00f3n definitiva aceptable para ambas partes\u00bb y advirti\u00f3 que solo conducir\u00e1 a \u00abpreservar la diferencia y llevar\u00eda a las partes a atrincherarse en sus respectivas posiciones, alej\u00e1ndolas del arreglo pr\u00e1ctico\u00bb.<\/p>\n<p>El litigio se remonta a marzo de 2018, cuando <strong>Guyana<\/strong> present\u00f3 una demanda ante la <strong>CIJ<\/strong> para que declare la \u00abvalidez jur\u00eddica y el efecto vinculante\u00bb de ese laudo, as\u00ed como el car\u00e1cter definitivo de la delimitaci\u00f3n fronteriza. <strong>Caracas<\/strong> declar\u00f3 el laudo nulo en 1962 al considerar que estuvo rodeado de supuestas irregularidades.<\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Venezuela<\/strong> ha reiterado en diversas ocasiones que no reconocer\u00e1 el fallo que emita la <strong>CIJ<\/strong>.\u00a0<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Caracas.- La Asamblea Nacional (AN, Parlamento) de Venezuela aprob\u00f3 este martes, por unanimidad, un acuerdo que respalda las acciones legales emprendidas por el Ejecutivo de Delcy Rodr\u00edguez en la disputa territorial que mantiene la naci\u00f3n caribe\u00f1a con Guyana sobre el Esequibo. El acuerdo, presentado por el diputado chavista Jos\u00e9 Vielma Mora en una sesi\u00f3n ordinaria<\/p>\n","protected":false},"author":1,"featured_media":40548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-40547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40547"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40548"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}