{"id":40527,"date":"2026-05-13T06:30:10","date_gmt":"2026-05-13T06:30:10","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/cuba-refuerza-la-vigilancia-en-fronteras-tras-brote-de-hantavirus-en-el-crucero-mv-hondius\/"},"modified":"2026-05-13T06:30:10","modified_gmt":"2026-05-13T06:30:10","slug":"cuba-refuerza-la-vigilancia-en-fronteras-tras-brote-de-hantavirus-en-el-crucero-mv-hondius","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/cuba-refuerza-la-vigilancia-en-fronteras-tras-brote-de-hantavirus-en-el-crucero-mv-hondius\/","title":{"rendered":"Cuba refuerza la vigilancia en fronteras tras brote de hantavirus en el crucero MV Hondius"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong>La Habana<\/strong>, 12 may (EFE).- El <strong>Ministerio de Salud P\u00fablica<\/strong> (<strong>Minsap<\/strong>) de <strong>Cuba<\/strong> resalt\u00f3 este martes que es necesario mantenerse \u00abalerta\u00bb y en vigilancia epidemiol\u00f3gica en las fronteras tras el brote de hantavirus en el crucero <strong>MV Hondius<\/strong>, aunque agreg\u00f3 que en la isla no hay motivos de alarma.<\/p>\n<ul class=\"wp-block-list\">\n<li>La viceministra de Salud P\u00fablica, <strong>Carilda Pe\u00f1a Garc\u00eda<\/strong>, declar\u00f3 a la televisi\u00f3n estatal que el hantavirus de la variante andina no es conocida en <strong>Cuba<\/strong>, pero s\u00ed en las <strong>Am\u00e9ricas<\/strong>, en pa\u00edses como <strong>Argentina<\/strong> y <strong>Chile<\/strong>, y en <strong>Asia<\/strong> y <strong>Europa<\/strong>.<\/li>\n<\/ul>\n<p>Y aunque afirm\u00f3 que su presencia en la isla \u00abhasta ahora no se ha documentado\u00bb, <strong>Pe\u00f1a<\/strong> consider\u00f3 que el hantavirus se puede introducir \u00abpor personas portadoras de la enfermedad que pueden llegar al pa\u00eds\u00bb.<\/p>\n<h2 class=\"wp-block-heading\">Vigilancia en fronteras<\/h2>\n<p>Por ello, insisti\u00f3 en se\u00f1alar la importancia de <strong>mantener la vigilancia<\/strong> en las fronteras puertos, aeropuertos y marinas, con \u00abla inspecci\u00f3n a buques y aeronaves para detectar la presencia de roedores\u00bb.<\/p>\n<p>La especialista del <strong>Minsap<\/strong> tambi\u00e9n subray\u00f3 que esta \u00abes una situaci\u00f3n que la poblaci\u00f3n debe conocer\u00bb y advirti\u00f3 que el contagio de la enfermedad con s\u00edntomas similares a los de un cuadro de gripe se produce por contacto directo.<\/p>\n<h3 class=\"wp-block-heading\">Brote en el crucero<\/h3>\n<p>El crucero <strong>MV Hondius<\/strong>, con 147 pasajeros y tripulantes de unos 23 pa\u00edses, comenz\u00f3 un periplo en <strong>Ushuaia<\/strong>, <strong>Argentina<\/strong>, que le llev\u00f3 a varias islas en el <strong>Atl\u00e1ntico<\/strong>, y durante el viaje aparecieron varios casos de hantavirus que han causado tres muertos.<\/p>\n<p>La <strong>Organizaci\u00f3n Mundial de la Salud<\/strong> (<strong>OMS<\/strong>) ha elevado a once el n\u00famero de casos positivos asociados al brote en el barco y ha manifestado que todos los casos sospechosos y confirmados han sido aislados y se est\u00e1n gestionando bajo una supervisi\u00f3n m\u00e9dica \u00abestricta\u00bb para minimizar el riesgo de cualquier transmisi\u00f3n posterior.<\/p>\n<p>Al respecto, el director general de la <strong>OMS<\/strong>, <strong>Tedros Adhanom<\/strong>, ha asegurado que la evaluaci\u00f3n del riesgo para la salud global ante este brote \u00absigue siendo baja\u00bb y que no hay nada que apunte a que vaya a haber un brote mayor, aunque tambi\u00e9n ha admitido que \u00abla situaci\u00f3n puede cambiar\u00bb por el elevado periodo de incubaci\u00f3n de alrededor de ocho semanas.\u00a0<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Habana, 12 may (EFE).- El Ministerio de Salud P\u00fablica (Minsap) de Cuba resalt\u00f3 este martes que es necesario mantenerse \u00abalerta\u00bb y en vigilancia epidemiol\u00f3gica en las fronteras tras el brote de hantavirus en el crucero MV Hondius, aunque agreg\u00f3 que en la isla no hay motivos de alarma. La viceministra de Salud P\u00fablica, Carilda<\/p>\n","protected":false},"author":1,"featured_media":40528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-40527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40527"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40527\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40528"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}