{"id":40517,"date":"2026-05-13T05:33:10","date_gmt":"2026-05-13T05:33:10","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/22-feminicidios-y-17-552-denuncias-de-violencia-en-enero-marzo-2026\/"},"modified":"2026-05-13T05:33:10","modified_gmt":"2026-05-13T05:33:10","slug":"22-feminicidios-y-17-552-denuncias-de-violencia-en-enero-marzo-2026","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/22-feminicidios-y-17-552-denuncias-de-violencia-en-enero-marzo-2026\/","title":{"rendered":"22 feminicidios y 17.552 denuncias de violencia en enero-marzo 2026"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong>Santo Domingo<\/strong>.- La <strong>Rep\u00fablica Dominicana<\/strong> registr\u00f3 22 feminicidios en el primer trimestre de 2026, tres de v\u00edctimas que hab\u00edan denunciado amenazas de muerte.<\/p>\n<p>Las cifras presentadas este martes por la <strong>Procuradur\u00eda General<\/strong> (<strong>PGR<\/strong>) en un bolet\u00edn estad\u00edstico sobre violencia de g\u00e9nero, intrafamiliar y delitos sexuales, correspondiente a enero-marzo de 2026, dan cuenta de que en este lapso se registraron 17.552 denuncias por estos cr\u00edmenes, con predominio de exparejas como agresores.<\/p>\n<p>El informe establece que aproximadamente el 89 % de las denuncias corresponde a violencia intrafamiliar y de pareja. Tambi\u00e9n identifica patrones, como el de un <strong>mayor <\/strong>n\u00famero de denuncias al inicio de la semana, as\u00ed como una incidencia predominante en personas entre los 18 y 35 a\u00f1os.<\/p>\n<p>En t\u00e9rminos de tipolog\u00eda, la violencia intrafamiliar representa el 52,49 % de las <strong>denuncias <\/strong>en el pa\u00eds, seguida por la violencia de g\u00e9nero con un 36,94 %, mientras que el 10,57 % corresponde a delitos sexuales.<\/p>\n<h3 class=\"wp-block-heading\">Tipos de violencia<\/h3>\n<p>Respecto al v\u00ednculo entre v\u00edctimas y agresores, la mayor incidencia corresponde a <strong>exparejas<\/strong>, con un 49 %, seguida de parejas actuales, un 18,25 %.<\/p>\n<p>En cuanto al perfil de los involucrados, los <strong>hombres <\/strong>concentran la mayor\u00eda de los casos como presuntos agresores, mientras que las mujeres figuran como principales v\u00edctimas.<\/p>\n<h2 class=\"wp-block-heading\">Antecedentes de 2025<\/h2>\n<p>En la <strong>Rep\u00fablica Dominicana<\/strong> se registraron 59 feminicidios cometidos por parejas o exparejas en el a\u00f1o 2025, seg\u00fan datos del <strong>Ministerio de Interior y Polic\u00eda<\/strong>.<\/p>\n<ul class=\"wp-block-list\">\n<li>Esta cifra represent\u00f3 una disminuci\u00f3n del 17 % en comparaci\u00f3n con los 71 casos reportados en 2024.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- La Rep\u00fablica Dominicana registr\u00f3 22 feminicidios en el primer trimestre de 2026, tres de v\u00edctimas que hab\u00edan denunciado amenazas de muerte. Las cifras presentadas este martes por la Procuradur\u00eda General (PGR) en un bolet\u00edn estad\u00edstico sobre violencia de g\u00e9nero, intrafamiliar y delitos sexuales, correspondiente a enero-marzo de 2026, dan cuenta de que en<\/p>\n","protected":false},"author":1,"featured_media":40518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40517"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40518"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}