{"id":40511,"date":"2026-05-13T05:00:28","date_gmt":"2026-05-13T05:00:28","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/jce-participara-en-tribunales-en-demandas-sobre-estado-civil-que-afecten-el-registro\/"},"modified":"2026-05-13T05:00:28","modified_gmt":"2026-05-13T05:00:28","slug":"jce-participara-en-tribunales-en-demandas-sobre-estado-civil-que-afecten-el-registro","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/jce-participara-en-tribunales-en-demandas-sobre-estado-civil-que-afecten-el-registro\/","title":{"rendered":"JCE participar\u00e1 en tribunales en demandas sobre estado civil que afecten el Registro"},"content":{"rendered":"<div id=\"nota-texto\">\n<p><strong>Santo Domingo<\/strong>. \u2013 La <strong>Junta Central Electoral<\/strong> (<strong>JCE<\/strong>) decidi\u00f3 y puso en conocimiento del <strong>Poder Judicial<\/strong> que, en lo adelante, comparecer\u00e1 y ser\u00e1 parte en los tribunales de la <strong>Rep\u00fablica Dominicana<\/strong> en las demandas relativas a los actos del estado civil, tales como la posesi\u00f3n de Estado, adopciones, impugnaciones de filiaci\u00f3n y todo proceso que pueda impactar directa o indirectamente al <strong>Registro Civil Dominicano<\/strong>.<\/p>\n<h2 class=\"wp-block-heading\">Decisi\u00f3n de la JCE<\/h2>\n<p>Esta decisi\u00f3n, tomada por los miembros del Pleno de la <strong>JCE<\/strong> en la sesi\u00f3n administrativa ordinaria celebrada el pasado 5 de mayo, ordena poner en conocimiento al juez presidente de la <strong>Suprema Corte de Justicia<\/strong> y presidente del <strong>Consejo del Poder Judicial<\/strong>, <strong>Luis Henry Molina<\/strong>, y en \u00e9l a todo el <strong>Poder Judicial<\/strong>, para los fines de lugar.<\/p>\n<h2 class=\"wp-block-heading\">Rol en estado civil<\/h2>\n<p>Se recuerda que <strong>JCE<\/strong> es un \u00f3rgano aut\u00f3nomo con funciones constitucionales de salvaguarda del <strong>Registro Civil<\/strong> y la identidad de los dominicanos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. \u2013 La Junta Central Electoral (JCE) decidi\u00f3 y puso en conocimiento del Poder Judicial que, en lo adelante, comparecer\u00e1 y ser\u00e1 parte en los tribunales de la Rep\u00fablica Dominicana en las demandas relativas a los actos del estado civil, tales como la posesi\u00f3n de Estado, adopciones, impugnaciones de filiaci\u00f3n y todo proceso que<\/p>\n","protected":false},"author":1,"featured_media":40512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40511"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40511\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40512"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}