{"id":40489,"date":"2026-05-13T03:10:02","date_gmt":"2026-05-13T03:10:02","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/ee-uu-autoriza-deportacion-hacia-rd-de-haitiano-detenido-por-presuntos-vinculos-con-pandillas\/"},"modified":"2026-05-13T03:10:02","modified_gmt":"2026-05-13T03:10:02","slug":"ee-uu-autoriza-deportacion-hacia-rd-de-haitiano-detenido-por-presuntos-vinculos-con-pandillas","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/13\/ee-uu-autoriza-deportacion-hacia-rd-de-haitiano-detenido-por-presuntos-vinculos-con-pandillas\/","title":{"rendered":"EE. UU. autoriza deportaci\u00f3n hacia RD de haitiano detenido por presuntos v\u00ednculos con pandillas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/05\/Ese-habeas-corpus-le-fue-denegado-en-2025.-Hoy-EE.UU_.-autorizo-deportarlo-hacia-RD.jpg-355x200.jpeg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #6e4448;margin-bottom: 5px;clear:both;max-width: 100%\" data-has-transparency=\"false\" data-dominant-color=\"6e4448\" \/><\/p>\n<p>EL NUEVO DIARIO,\u00a0MIAMI, EE. UU.\u2013 Las autoridades estadounidenses autorizaron la deportaci\u00f3n hacia Rep\u00fablica Dominicana del ciudadano haitiano Dimitri Albert Edouard Vorbe, quien se encontraba detenido por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) en Miami bajo acusaciones de representar un riesgo para la pol\u00edtica exterior de Estados Unidos.<\/p>\n<p data-start=\"460\" data-end=\"774\">La decisi\u00f3n sali\u00f3 a relucir en medio del reciente acuerdo migratorio suscrito entre Estados Unidos y Rep\u00fablica Dominicana sobre traslado temporal de nacionales de terceros pa\u00edses, aunque las autoridades aseguraron que dicho convenio excluye a ciudadanos haitianos.<\/p>\n<p data-start=\"776\" data-end=\"970\">Vorbe hab\u00eda presentado en 2025 una petici\u00f3n de habeas corpus ante una corte federal del Distrito Sur de Florida, mediante la cual alegaba que su detenci\u00f3n era ilegal y violaba el debido proceso.\u00a0De acuerdo con el expediente judicial, el haitiano manten\u00eda un proceso migratorio activo para obtener la residencia permanente en Estados Unidos a trav\u00e9s de una petici\u00f3n familiar presentada por su hijo, ciudadano estadounidense. Adem\u00e1s, contaba con Estatus de Protecci\u00f3n Temporal (TPS) para haitianos.<\/p>\n<p data-start=\"1275\" data-end=\"1430\">Sin embargo, en septiembre de 2025 fue arrestado por agentes de ICE en su residencia en Miami y posteriormente trasladado al Centro de Procesamiento Krome.<\/p>\n<p data-start=\"1432\" data-end=\"1690\">El Gobierno estadounidense aleg\u00f3, mediante un memorando atribuido al entonces secretario de Estado Marco Rubio, que Vorbe habr\u00eda participado en actividades vinculadas a violencia y apoyo a pandillas en Hait\u00ed, contribuyendo a la desestabilizaci\u00f3n de ese pa\u00eds.<\/p>\n<p data-start=\"1692\" data-end=\"1876\">La defensa sostuvo ante el tribunal federal que no exist\u00edan pruebas concretas contra su cliente y argument\u00f3 que Vorbe no posee antecedentes criminales ni en Estados Unidos ni en Hait\u00ed.<\/p>\n<p data-start=\"1878\" data-end=\"2060\">Asimismo, los abogados Anthony Dominguez y Maitte Barrientos afirmaron que el Gobierno estaba aplicando de manera incorrecta las disposiciones sobre detenci\u00f3n migratoria obligatoria.<\/p>\n<p data-start=\"2062\" data-end=\"2252\">En la acci\u00f3n judicial, los representantes legales solicitaron una audiencia de fianza o, en su defecto, la liberaci\u00f3n inmediata de Vorbe. No obstante, el habeas corpus fue rechazado en 2025.<\/p>\n<p data-start=\"2254\" data-end=\"2359\" data-is-last-node=\"\" data-is-only-node=\"\">Tras esa decisi\u00f3n, las autoridades estadounidenses autorizaron su deportaci\u00f3n hacia Rep\u00fablica Dominicana.<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/ee-uu-autoriza-deportacion-hacia-rd-de-haitiano-detenido-por-presuntos-vinculos-con-pandillas\/\">EE. UU. autoriza deportaci\u00f3n hacia RD de haitiano detenido por presuntos v\u00ednculos con pandillas<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO,\u00a0MIAMI, EE. UU.\u2013 Las autoridades estadounidenses autorizaron la deportaci\u00f3n hacia Rep\u00fablica Dominicana del ciudadano haitiano Dimitri Albert Edouard Vorbe, quien se encontraba detenido por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) en Miami bajo acusaciones de representar un riesgo para la pol\u00edtica exterior de Estados Unidos. La decisi\u00f3n sali\u00f3 a relucir<\/p>\n","protected":false},"author":1,"featured_media":40490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40489"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40490"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}