{"id":40452,"date":"2026-05-12T23:30:35","date_gmt":"2026-05-12T23:30:35","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/12\/maradona-suspendio-medicamento-para-hipertension-poco-antes-de-su-muerte-segun-testigos\/"},"modified":"2026-05-12T23:30:35","modified_gmt":"2026-05-12T23:30:35","slug":"maradona-suspendio-medicamento-para-hipertension-poco-antes-de-su-muerte-segun-testigos","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/12\/maradona-suspendio-medicamento-para-hipertension-poco-antes-de-su-muerte-segun-testigos\/","title":{"rendered":"Maradona suspendi\u00f3 medicamento para hipertensi\u00f3n poco antes de su muerte, seg\u00fan testigos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2025\/05\/maradona-355x200.jpg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #6a6767;margin-bottom: 5px;clear:both;max-width: 100%\" data-has-transparency=\"false\" data-dominant-color=\"6a6767\" \/><\/p>\n<p>BUENOS AIRES. &#8211; Diego Armando Maradona dej\u00f3 de tomar un medicamento para la hipertensi\u00f3n poco tiempo antes de su muerte, el 25 de noviembre de 2020, seg\u00fan surgi\u00f3 este martes de la declaraci\u00f3n de dos m\u00e9dicos que lo trataron en una cl\u00ednica privada previo a su fallecimiento.<\/p>\n<p>La muerte del astro, seg\u00fan indic\u00f3 la autopsia, se produjo a causa de un \u00abedema agudo de pulm\u00f3n en un paciente con una miocardiopat\u00eda cr\u00f3nica reagudizada por la insuficiencia card\u00edaca\u00bb.<\/p>\n<p>Uno de los ejes centrales de la Fiscal\u00eda en el juicio para determinar las causas de su fallecimiento consiste en demostrar que Maradona ten\u00eda antecedentes y patolog\u00edas card\u00edacas que su equipo m\u00e9dico, imputado en la causa, desatendi\u00f3.<\/p>\n<p>En su declaraci\u00f3n de este martes, el cardi\u00f3logo Oscar Franco, quien trat\u00f3 a Maradona en la cl\u00ednica privada Ipensa de la ciudad de La Plata el 2 de septiembre de 2020, afirm\u00f3 que en ese entonces el astro tomaba una medicaci\u00f3n para la hipertensi\u00f3n llamada Losartan.<\/p>\n<p>Marcos Correa, m\u00e9dico cl\u00ednico que atendi\u00f3 a Maradona el 2 noviembre de ese a\u00f1o en esa misma cl\u00ednica, destac\u00f3 en su testimonio de este martes que, al registrar aquel d\u00eda la medicaci\u00f3n que tomaba el astro, hall\u00f3 tres medicamentos psiqui\u00e1tricos pero ninguno para la hipertensi\u00f3n.<\/p>\n<p>Seg\u00fan explic\u00f3 Franco, la suspensi\u00f3n de esa medicaci\u00f3n, sobre la cual no recibieron explicaciones, puede provocar \u00abcambios a nivel arterial\u00bb, despu\u00e9s \u00aba nivel miocardio\u00bb y una posible \u00abfalla card\u00edaca\u00bb.<\/p>\n<p>El cardi\u00f3logo record\u00f3 adem\u00e1s que durante aquella consulta de septiembre se le realizaron al exfutbolista ex\u00e1menes cardiol\u00f3gicos de rutina que \u00abno arrojaron datos anormales\u00bb, pese a lo cual, debido a los antecedentes del paciente, sugiri\u00f3 realizar un estudio de perfusi\u00f3n, que \u00absirve para tratar de determinar la probabilidad de enfermedad coronaria\u00bb.<\/p>\n<p>Franco subray\u00f3 que ese procedimiento no resultaba invasivo y tomaba solo unos 15 minutos, antes de enfatizar que finalmente el estudio no se llev\u00f3 a cabo \u00abpor decisi\u00f3n del m\u00e9dico que estaba a cargo\u00bb de Maradona, el neurocirujano Leopoldo Luque.<\/p>\n<p>La Fiscal\u00eda expuso luego un mensaje de audio en el que se escucha a Luque decir a Franco que un estudio de perfusi\u00f3n le parec\u00eda \u00abdemasiado\u00bb, antes de agregar: \u00abLa idea es hacerle algo general y algo r\u00e1pido por el tema del coronavirus y porque a \u00e9l no le agrada mucho estar rodeado de m\u00e9dicos\u00bb.<\/p>\n<p>Los dos testigos de este martes se refirieron a Luque, principal acusado en el juicio, como \u201cel m\u00e9dico de cabecera de Maradona\u201d, algo que han ratificado numerosos testigos a lo largo del proceso con t\u00e9rminos como \u00abm\u00e9dico a cargo\u00bb o \u00abm\u00e9dico tratante\u00bb, pero que la defensa del neurocirujano niega.<\/p>\n<p>Adem\u00e1s de Luque, son juzgados en este proceso la psiquiatra Agustina Cosachov, el psicoanalista Carlos D\u00edaz, la doctora y coordinadora de la empresa Swiss Medical Nancy Forlini, el m\u00e9dico Pedro Di Spagna, el coordinador de enfermeros Mariano Perroni y el enfermero Ricardo Almir\u00f3n.<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/maradona-suspendio-medicamento-para-hipertension-poco-antes-de-su-muerte-segun-testigos\/\">Maradona suspendi\u00f3 medicamento para hipertensi\u00f3n poco antes de su muerte, seg\u00fan testigos<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BUENOS AIRES. &#8211; Diego Armando Maradona dej\u00f3 de tomar un medicamento para la hipertensi\u00f3n poco tiempo antes de su muerte, el 25 de noviembre de 2020, seg\u00fan surgi\u00f3 este martes de la declaraci\u00f3n de dos m\u00e9dicos que lo trataron en una cl\u00ednica privada previo a su fallecimiento. La muerte del astro, seg\u00fan indic\u00f3 la autopsia,<\/p>\n","protected":false},"author":1,"featured_media":34393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-40452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deporte"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40452"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/34393"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}