{"id":40437,"date":"2026-05-12T22:20:48","date_gmt":"2026-05-12T22:20:48","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/05\/12\/embajada-de-ee-uu-afirma-revocara-visas-cuando-exista-informacion-adversa-sobre-posible-inelegibilidad\/"},"modified":"2026-05-12T22:20:48","modified_gmt":"2026-05-12T22:20:48","slug":"embajada-de-ee-uu-afirma-revocara-visas-cuando-exista-informacion-adversa-sobre-posible-inelegibilidad","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/05\/12\/embajada-de-ee-uu-afirma-revocara-visas-cuando-exista-informacion-adversa-sobre-posible-inelegibilidad\/","title":{"rendered":"Embajada de EE. UU. afirma revocar\u00e1 visas cuando exista informaci\u00f3n adversa sobre posible inelegibilidad"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/05\/Embajada-de-EE.-UU.-afirma-revocara-visas-cuando-exista-informacion-adversa-sobre-posible-inelegibilidad.jpg-1-355x200.jpeg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #744847;margin-bottom: 5px;clear:both;max-width: 100%\" data-has-transparency=\"false\" data-dominant-color=\"744847\" \/><\/p>\n<p>EL NUEVO DIARIO,\u00a0SANTO DOMINGO.\u2013 La Embajada de los Estados Unidos en Santo Domingo indic\u00f3 que el Departamento de Estado revocar\u00e1 visas cuando exista informaci\u00f3n adversa que indique una posible inelegibilidad o la p\u00e9rdida del derecho a la misma.<\/p>\n<p>La declaraci\u00f3n fue enviada a este medio luego de que se solicitara informaci\u00f3n a la sede diplom\u00e1tica tras una publicaci\u00f3n realizada por el abogado y comunicador Rafael Linares Guerrero en su cuenta de X, sobre la supuesta cancelaci\u00f3n del visado estadounidense de la diputada Leyvi Bautista y su esposo, Luguer Gaciller.<\/p>\n<p>\u201cMe informan que el @StateDept conjuntamente con la @EmbajadaUSAenRD, le cancel\u00f3 el visado norteamericano a la diputada Leyvi Bautista y a su esposo Luguel Gaciller\u201d, public\u00f3 Linares la tarde del domingo.<\/p>\n<p>Al ser consultada sobre el tema, la Embajada estadounidense expres\u00f3 mediante correo electr\u00f3nico: \u00abEl Departamento de Estado revocar\u00e1 visas cuando exista informaci\u00f3n adversa que indique una posible inelegibilidad para la visa o la p\u00e9rdida del derecho a la misma\u00bb.<\/p>\n<p>\u00abDebido a la confidencialidad de los registros de visas, no hacemos comentarios sobre las acciones del Departamento con respecto a casos espec\u00edficos\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/embajada-de-ee-uu-afirma-revocara-visas-cuando-exista-informacion-adversa-sobre-posible-inelegibilidad\/\">Embajada de EE. UU. afirma revocar\u00e1 visas cuando exista informaci\u00f3n adversa sobre posible inelegibilidad<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO,\u00a0SANTO DOMINGO.\u2013 La Embajada de los Estados Unidos en Santo Domingo indic\u00f3 que el Departamento de Estado revocar\u00e1 visas cuando exista informaci\u00f3n adversa que indique una posible inelegibilidad o la p\u00e9rdida del derecho a la misma. La declaraci\u00f3n fue enviada a este medio luego de que se solicitara informaci\u00f3n a la sede diplom\u00e1tica<\/p>\n","protected":false},"author":1,"featured_media":40438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-40437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=40437"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/40437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/40438"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=40437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=40437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=40437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}