{"id":29602,"date":"2026-03-24T00:14:39","date_gmt":"2026-03-24T00:14:39","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/03\/24\/abinader-llega-a-paris-para-reunirse-con-macron-y-participar-en-foro-global-anticorrupcion-e-integridad\/"},"modified":"2026-03-24T00:14:39","modified_gmt":"2026-03-24T00:14:39","slug":"abinader-llega-a-paris-para-reunirse-con-macron-y-participar-en-foro-global-anticorrupcion-e-integridad","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/03\/24\/abinader-llega-a-paris-para-reunirse-con-macron-y-participar-en-foro-global-anticorrupcion-e-integridad\/","title":{"rendered":"Abinader llega a Par\u00eds para reunirse con Macron y participar en Foro Global Anticorrupci\u00f3n e Integridad"},"content":{"rendered":"<p><img decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.05.19-PM-2-355x200.jpeg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #625045;margin-bottom: 5px;clear:both;max-width: 100%\" loading=\"lazy\" data-has-transparency=\"false\" data-dominant-color=\"625045\" \/><\/p>\n<p>EL NUEVO DIARIO, PARIS, FRANCIA. &#8211; El presidente Luis Abinader arrib\u00f3 la noche de este lunes a Par\u00eds, Francia, en una visita oficial en la que se llevar\u00e1 a cabo un nuevo encuentro con el presidente franc\u00e9s, Emmanuel Macron, y participar\u00e1 en la ceremonia inaugural del Foro Global Anticorrupci\u00f3n e Integridad que organiza la\u00a0Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3mico\u00a0(OCDE).<\/p>\n<p>En la sede de la OCDE, el jefe de Estado tambi\u00e9n participar\u00e1 en la firma de un Memorandum de Entendimiento entre la Rep\u00fablica Dominicana y dicha organizaci\u00f3n, aceptando la invitaci\u00f3n de su secretario general Mathias Cormann, quien adem\u00e1s inform\u00f3 que el presidente Abinader estar\u00eda participando en el 18.\u00ba Foro Econ\u00f3mico Internacional sobre Am\u00e9rica Latina y el Caribe, que formar\u00e1 parte del calendario de actividades del d\u00e9cimo aniversario del Programa Regional de la OCDE para Am\u00e9rica Latina y el Caribe el 2 de junio de 2026.<\/p>\n<p>El Foro Global Anticorrupci\u00f3n e Integridad de la OCDE, que inicia este martes, es un espacio clave para promover pol\u00edticas de transparencia, rendici\u00f3n de cuentas y fortalecimiento institucional.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"403f40\" data-has-transparency=\"false\" style=\"--dominant-color: #403f40\" class=\"alignnone size-full wp-image-3058922 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.05.19-PM.jpeg?resize=640%2C427&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Al presidente le acompa\u00f1an, los ministros, de la Presidencia, Jos\u00e9 Ignacio Paliza; de Relaciones Exteriores, Roberto \u00c1lvarez; de Educaci\u00f3n, Luis Miguel De Camps; la directora de \u00c9tica e Integridad Gubernamental, Milagros Ortiz Bosch; y tambi\u00e9n su hija Esther Abinader, el jefe del Cuerpo de Seguridad Presidencial, Jimmy Arias, y sus asistentes Eilyn Beltr\u00e1n y Noelia Shephard.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"4e433d\" data-has-transparency=\"false\" style=\"--dominant-color: #4e433d\" class=\"alignnone size-full wp-image-3058921 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.05.19-PM-1.jpeg?resize=640%2C427&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Otros encuentros que sostendr\u00e1 el jefe de Estado ser\u00e1n con l\u00edderes empresariales, con el objetivo de impulsar inversiones y cooperaci\u00f3n econ\u00f3mica.<\/p>\n<p>Asimismo, se reunir\u00e1 con Aidan Eyakuze y sostendr\u00e1 un almuerzo de trabajo con Mathias Cormann, secretario general de la OCDE. La jornada culminar\u00e1 con el esperado encuentro entre Luis Abinader y Emmanuel Macron, seguido de un acercamiento con la comunidad dominicana residente en Francia.<\/p>\n<p><img decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"615351\" data-has-transparency=\"false\" style=\"--dominant-color: #615351\" loading=\"lazy\" class=\"alignnone size-full wp-image-3058920 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-23-at-8.05.20-PM.jpeg?resize=640%2C427&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>El mi\u00e9rcoles 25, el presidente encabezar\u00e1 un desayuno con empresarios franceses enfocado en fortalecer los v\u00ednculos comerciales y atraer inversiones hacia sectores estrat\u00e9gicos como infraestructura, transporte, log\u00edstica, zonas francas y energ\u00edas renovables.<\/p>\n<p>La salida del jefe de Estado, desde Par\u00eds, est\u00e1 prevista para horas de la tarde de ese mismo d\u00eda.<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/abinader-llega-a-paris-para-reunirse-con-macron-y-participar-en-foro-global-anticorrupcion-e-integridad\/\">Abinader llega a Par\u00eds para reunirse con Macron y participar en Foro Global Anticorrupci\u00f3n e Integridad<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO, PARIS, FRANCIA. &#8211; El presidente Luis Abinader arrib\u00f3 la noche de este lunes a Par\u00eds, Francia, en una visita oficial en la que se llevar\u00e1 a cabo un nuevo encuentro con el presidente franc\u00e9s, Emmanuel Macron, y participar\u00e1 en la ceremonia inaugural del Foro Global Anticorrupci\u00f3n e Integridad que organiza la\u00a0Organizaci\u00f3n para<\/p>\n","protected":false},"author":1,"featured_media":29603,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-29602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/29602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=29602"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/29602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/29603"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=29602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=29602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=29602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}