{"id":28999,"date":"2026-03-21T00:17:04","date_gmt":"2026-03-21T00:17:04","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/03\/21\/eddy-olivares-asegura-en-rd-no-se-justifica-el-trabajo-infantil-somos-un-pais-que-avanza-realiza-operativo\/"},"modified":"2026-03-21T00:17:04","modified_gmt":"2026-03-21T00:17:04","slug":"eddy-olivares-asegura-en-rd-no-se-justifica-el-trabajo-infantil-somos-un-pais-que-avanza-realiza-operativo","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/03\/21\/eddy-olivares-asegura-en-rd-no-se-justifica-el-trabajo-infantil-somos-un-pais-que-avanza-realiza-operativo\/","title":{"rendered":"Eddy Olivares asegura en RD no se justifica el trabajo infantil: \u00abSomos un pa\u00eds que avanza\u00bb; realiza operativo"},"content":{"rendered":"<p><img decoding=\"async\" width=\"355\" height=\"200\" src=\"https:\/\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-20-at-5.16.15-PM-1-355x200.jpeg\" class=\"webfeedsFeaturedVisual not-transparent wp-post-image\" alt=\"\" style=\"--dominant-color: #a8b4ba;margin-bottom: 5px;clear:both;max-width: 100%\" loading=\"lazy\" data-has-transparency=\"false\" data-dominant-color=\"a8b4ba\" \/><\/p>\n<p>EL NUEVO DIARIO, SANTO DOMINGO. &#8211;\u00a0El ministro de Trabajo, Eddy Olivares Ortega, afirm\u00f3 este viernes que en la actualidad no existe justificaci\u00f3n para el trabajo infantil en Rep\u00fablica Dominicana, al destacar que el Estado tiene la responsabilidad de garantizar las condiciones necesarias para el desarrollo integral de los ni\u00f1os.<\/p>\n<p>\u201cHoy somos un pa\u00eds que avanza y que tiene la capacidad de ofrecer a nuestros ni\u00f1os la oportunidad de estudiar y recrearse\u201d, expres\u00f3 el funcionario, al encabezar un operativo de prevenci\u00f3n y erradicaci\u00f3n del trabajo infantil en sectores vulnerables de La Nueva Barquita.<\/p>\n<p>La jornada, organizada por el Ministerio de Trabajo, tuvo como objetivo sensibilizar a la poblaci\u00f3n y reforzar las acciones dirigidas a proteger los derechos de la ni\u00f1ez, en cumplimiento del art\u00edculo 56 de la Constituci\u00f3n, que establece como deber del Estado prevenir y eliminar el trabajo infantil.\u00a0<img decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"9b9b99\" data-has-transparency=\"false\" style=\"--dominant-color: #9b9b99\" loading=\"lazy\" class=\"alignnone size-full wp-image-3056127 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/Eddy-Olivares-asegura-en-RD-no-se-justifica-el-trabajo-infantil-2.jpeg?resize=640%2C400&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"400\" \/> Durante su intervenci\u00f3n, Olivares Ortega subray\u00f3 que la infancia es una etapa esencial en la vida humana, marcada por la inocencia y advirti\u00f3 que el trabajo infantil priva a los menores de ese per\u00edodo, al imponerles responsabilidades propias de los adultos.<\/p>\n<p>\u201cLa infancia debe ser ese tiempo m\u00e1gico que solo se vive una vez\u201d, enfatiz\u00f3 el ministro, tras reiterar que este tipo de iniciativas tambi\u00e9n buscan crear conciencia en los adultos sobre su rol en la protecci\u00f3n de los ni\u00f1os, ni\u00f1as y adolescentes.<\/p>\n<p>El operativo se desarroll\u00f3 en el Polit\u00e9cnico Sor \u00c1ngeles Valls Fe y Alegr\u00eda, bajo la coordinaci\u00f3n de la Direcci\u00f3n de Prevenci\u00f3n y Erradicaci\u00f3n del Trabajo Infantil (DPETI) e incluy\u00f3 charlas de sensibilizaci\u00f3n, asistencia social y servicios m\u00e9dicos para los residentes de la comunidad.<\/p>\n<p><img decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"a5a9a9\" data-has-transparency=\"false\" style=\"--dominant-color: #a5a9a9\" loading=\"lazy\" class=\"alignnone size-full wp-image-3056128 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/Eddy-Olivares-asegura-en-RD-no-se-justifica-el-trabajo-infantil-3.jpeg?resize=640%2C426&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"426\" \/><\/p>\n<p>En ese sentido, la directora de Prevenci\u00f3n y Erradicaci\u00f3n del Trabajo Infantil, Hilaria Hilario, explic\u00f3 que cada acci\u00f3n responde a un enfoque integral orientado a sensibilizar, prevenir y erradicar esta problem\u00e1tica, garantizando que los menores crezcan en entornos seguros, con acceso a educaci\u00f3n, salud y oportunidades de desarrollo.<\/p>\n<p>Durante la jornada, instituciones como el Consejo Nacional para la Ni\u00f1ez y la Adolescencia (Conani), Sup\u00e9rate e Inespre ofrecieron orientaci\u00f3n y apoyo social, mientras que se brindaron servicios de salud, incluyendo consultas oftalmol\u00f3gicas, entrega de medicamentos y lentes bajo prescripci\u00f3n m\u00e9dica.<\/p>\n<p>Asimismo, participaron el Ministerio de Interior y Polic\u00eda, el programa RD Trabaja y \u00e1reas especializadas del Ministerio de Trabajo, que ofrecieron acompa\u00f1amiento institucional, asistencia judicial y orientaci\u00f3n en seguridad y salud laboral.<\/p>\n<p><img decoding=\"async\" data-recalc-dims=\"1\" data-dominant-color=\"90938e\" data-has-transparency=\"false\" style=\"--dominant-color: #90938e\" loading=\"lazy\" class=\"alignnone size-full wp-image-3056125 not-transparent\" src=\"https:\/\/i0.wp.com\/nuevodiario-assets.s3.us-east-2.amazonaws.com\/wp-content\/uploads\/2026\/03\/Eddy-Olivares-asegura-en-RD-no-se-justifica-el-trabajo-infantil-1.jpeg?resize=640%2C426&#038;quality=100&#038;ssl=1\" alt=\"\" width=\"640\" height=\"426\" \/><\/p>\n<p>De igual forma, se desarrollaron actividades educativas y recreativas dirigidas a ni\u00f1os y ni\u00f1as, adem\u00e1s de la entrega de alimentos por parte de los Comedores Econ\u00f3micos, como parte del respaldo a las familias de la zona.<\/p>\n<p>En el acto tambi\u00e9n intervino el padre Gregorio Alegr\u00eda Armend\u00e1riz, quien valor\u00f3 las acciones que impulsa el Ministerio de Trabajo en favor de la ni\u00f1ez, especialmente en La Nueva Barquita, una comunidad que alberga a m\u00e1s de seis mil habitantes en 1,700 apartamentos construidos por el Estado.<\/p>\n<p>La actividad cont\u00f3 con la presencia de la viceministra de Trabajo Infantil y Sectores Vulnerables, Dulce Mercedes Qui\u00f1ones; el viceministro de Seguridad Social, Ram\u00f3n Efr\u00e9n Cuello; la gobernadora provincial, Lucrecia Santana Leyba; la diputada Patricia N\u00fa\u00f1ez y el gerente del Patronato de La Nueva Barquita, Alexander Grull\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>La entrada <a href=\"https:\/\/elnuevodiario.com.do\/eddy-olivares-asegura-en-rd-no-se-justifica-el-trabajo-infantil-somos-un-pais-que-avanza-realiza-operativo\/\">Eddy Olivares asegura en RD no se justifica el trabajo infantil: \u00abSomos un pa\u00eds que avanza\u00bb; realiza operativo<\/a> se public\u00f3 primero en <a href=\"https:\/\/elnuevodiario.com.do\">El Nuevo Diario (Rep\u00fablica Dominicana)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EL NUEVO DIARIO, SANTO DOMINGO. &#8211;\u00a0El ministro de Trabajo, Eddy Olivares Ortega, afirm\u00f3 este viernes que en la actualidad no existe justificaci\u00f3n para el trabajo infantil en Rep\u00fablica Dominicana, al destacar que el Estado tiene la responsabilidad de garantizar las condiciones necesarias para el desarrollo integral de los ni\u00f1os. \u201cHoy somos un pa\u00eds que avanza<\/p>\n","protected":false},"author":1,"featured_media":29000,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-28999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/28999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=28999"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/28999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/29000"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=28999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=28999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=28999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}