{"id":2676,"date":"2025-11-11T23:12:26","date_gmt":"2025-11-11T23:12:26","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2025\/11\/11\/autoridades-informan-ya-se-ha-restablecido-el-15-del-servicio-electrico-tras-apagon-el-nuevo-diario-republica-dominicana\/"},"modified":"2025-11-11T23:12:26","modified_gmt":"2025-11-11T23:12:26","slug":"autoridades-informan-ya-se-ha-restablecido-el-15-del-servicio-electrico-tras-apagon-el-nuevo-diario-republica-dominicana","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2025\/11\/11\/autoridades-informan-ya-se-ha-restablecido-el-15-del-servicio-electrico-tras-apagon-el-nuevo-diario-republica-dominicana\/","title":{"rendered":"Autoridades informan ya se ha restablecido el 15 % del servicio el\u00e9ctrico tras apag\u00f3n \u2013 El Nuevo Diario (Rep\u00fablica Dominicana)"},"content":{"rendered":"<p><i class=\"bi bi-camera-fill\" style=\"font-size:18px; color:var(--rojo)\"\/> Joel Santos. (Foto: Direcci\u00f3n de Comunicaciones de Energ\u00eda y Minas)<\/p>\n<div>\n<p>\u00a0<\/p>\n<p>EL NUEVO DIARIO, SANTO DOMINGO. \u2013 El ministro de Energ\u00eda y Minas, Joel Santos Echavarr\u00eda inform\u00f3 la noche de este viernes que ya se ha restablecido alrededor del 15 % del servicio el\u00e9ctrico nacional, tras la aver\u00eda registrada a la 1:23 de la tarde en la subestaci\u00f3n San Pedro I, que provoc\u00f3 una interrupci\u00f3n general del suministro en gran parte del pa\u00eds.<\/p>\n<p>Durante una rueda de prensa en el Centro de Control de Energ\u00eda, Santos Echavarr\u00eda explic\u00f3 que el sistema avanza de manera progresiva hacia su recuperaci\u00f3n, gracias al trabajo continuo de los equipos t\u00e9cnicos.<\/p>\n<p>\u201cEn estos momentos ya contamos con m\u00e1s de 527 megavatios generando, lo que representa m\u00e1s de un 15 % de la demanda nacional y este n\u00famero seguir\u00e1 increment\u00e1ndose conforme avance el proceso de estabilizaci\u00f3n\u201d, precis\u00f3.<\/p>\n<p>El funcionario detall\u00f3 que las primeras plantas en sincronizarse con el sistema fueron las hidroel\u00e9ctricas, seguidas de algunas t\u00e9rmicas, como parte de un proceso gradual dise\u00f1ado para garantizar la estabilidad y seguridad del sistema interconectado. Algunas zonas de Santiago, San Crist\u00f3bal, Santo Domingo Norte y parte del sur del pa\u00eds ya comenzaron a recibir energ\u00eda.<\/p>\n<p>Asimismo, anunci\u00f3 que los servicios de transporte p\u00fablico \u2014Metro de Santo Domingo, Telef\u00e9ricos de Los Alcarrizos, Sabana Perdida y Santiago, adem\u00e1s de la Omsa\u2014 est\u00e1n operando nuevamente y de forma gratuita, con una extensi\u00f3n de dos horas en su horario habitual para facilitar la movilidad ciudadana durante la contingencia.<\/p>\n<p>Santos Echavarr\u00eda reiter\u00f3 que se ha activado el Comit\u00e9 de Fallas para realizar una investigaci\u00f3n t\u00e9cnica exhaustiva sobre las causas del evento, descartando de momento cualquier indicio de sabotaje.<\/p>\n<p>\u201cEl sistema el\u00e9ctrico es complejo y requiere de un an\u00e1lisis profundo antes de ofrecer un informe definitivo\u201d, subray\u00f3.<\/p>\n<p>Finalmente, el ministro pidi\u00f3 comprensi\u00f3n a la ciudadan\u00eda por los inconvenientes ocasionados y garantiz\u00f3 que todo el equipo del sector energ\u00e9tico permanece concentrado en restablecer el servicio de manera r\u00e1pida, segura y transparente, manteniendo informada a la poblaci\u00f3n en cada etapa del proceso.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><h3 class=\"jp-relatedposts-headline\"><em>Relacionado<\/em><\/h3>\n<\/p>\n<p>\t\t\t\t\t\t<!-- .entry-footer --><br \/>\n\t\t\t\t\t\t<!-- \n\n<div data-type=\"_mgwidget\" data-widget-id=\"1743501\"><\/div>\n\n  -->\n\t\t\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Joel Santos. (Foto: Direcci\u00f3n de Comunicaciones de Energ\u00eda y Minas) \u00a0 EL NUEVO DIARIO, SANTO DOMINGO. \u2013 El ministro de Energ\u00eda y Minas, Joel Santos Echavarr\u00eda inform\u00f3 la noche de este viernes que ya se ha restablecido alrededor del 15 % del servicio el\u00e9ctrico nacional, tras la aver\u00eda registrada a la 1:23 de la tarde<\/p>\n","protected":false},"author":1,"featured_media":2677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/2676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=2676"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/2676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/2677"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=2676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=2676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=2676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}