{"id":17121,"date":"2026-01-24T17:40:49","date_gmt":"2026-01-24T17:40:49","guid":{"rendered":"https:\/\/acronoticias.com\/index.php\/2026\/01\/24\/lo-sorprenden-dentro-de-vehiculo-cuando-agredia-sexualmente-a-una-nina\/"},"modified":"2026-01-24T17:40:49","modified_gmt":"2026-01-24T17:40:49","slug":"lo-sorprenden-dentro-de-vehiculo-cuando-agredia-sexualmente-a-una-nina","status":"publish","type":"post","link":"https:\/\/acronoticias.com\/index.php\/2026\/01\/24\/lo-sorprenden-dentro-de-vehiculo-cuando-agredia-sexualmente-a-una-nina\/","title":{"rendered":"Lo sorprenden dentro de veh\u00edculo cuando agred\u00eda sexualmente a una ni\u00f1a"},"content":{"rendered":"<div id=\"mvp-content-main\">\n<p>Agentes de la Direcci\u00f3n Especializada de Atenci\u00f3n a la Mujer y Violencia Intrafamiliar (DEAMVI), de la Polic\u00eda Nacional, informaron sobre la detenci\u00f3n de un hombre de 73 a\u00f1os, se\u00f1alado como presunto autor de manosear a una ni\u00f1a de 8 a\u00f1os, a quien ofrec\u00eda servicio de transporte escolar.<\/p>\n<p>El detenido, cuya identidad se hace reserva por el momento, residente en el sector Las Malvinas de Herrera, Santo Domingo Oeste, quien fue apresado tras ser denunciado por el conductor de un cami\u00f3n que asegur\u00f3 haberlo sorprendido agrediendo sexualmente a la ni\u00f1a alrededor de las 3:40 de la tarde, mientras se desplazaba en un carro por la avenida Luper\u00f3n.<\/p>\n<p>Tras esta situaci\u00f3n fue emitida una alerta a trav\u00e9s del Sistema Nacional de Atenci\u00f3n a Emergencias y Seguridad 9-1-1, llegando a la escena agentes policiales del \u00e1rea preventiva.<\/p>\n<p>De acuerdo con el informe preliminar, el imputado fue sorprendido dentro de un veh\u00edculo, donde presuntamente comet\u00eda el hecho en perjuicio de la ni\u00f1a, cuya identidad se hace reservas. La peque\u00f1a se encontraba bajo custodia del ahora investigado en calidad de estudiante transportada.<\/p>\n<p>La ni\u00f1a es representada legalmente por su madre, cuya identidad tambi\u00e9n se hace reserva.<\/p>\n<p>Tras su detenci\u00f3n, el caso ser\u00e1 puesto en conocimiento del Ministerio P\u00fablico, brind\u00e1ndose de inmediato la debida asistencia y acompa\u00f1amiento a la v\u00edctima, conforme a los protocolos establecidos.<\/p>\n<p>Asimismo, se inform\u00f3 que el caso ser\u00e1 remitido a la Jurisdicci\u00f3n de Ni\u00f1os, Ni\u00f1as y Adolescentes del Ministerio P\u00fablico, para los fines legales correspondientes.<\/p>\n<p>La Polic\u00eda Nacional, a trav\u00e9s de DEAMVI, reafirma su compromiso de proteger los derechos de la ni\u00f1ez y de actuar con firmeza ante cualquier hecho que atente contra su integridad f\u00edsica y emocional.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"Agentes de la Direcci\u00f3n Especializada de Atenci\u00f3n a la Mujer y Violencia&hellip;\n","protected":false},"author":1,"featured_media":13661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17121","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/17121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/comments?post=17121"}],"version-history":[{"count":0,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/posts\/17121\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media\/13661"}],"wp:attachment":[{"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/media?parent=17121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/categories?post=17121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acronoticias.com\/index.php\/wp-json\/wp\/v2\/tags?post=17121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}